{"id":455,"date":"2023-08-23T20:12:46","date_gmt":"2023-08-23T23:12:46","guid":{"rendered":"https:\/\/iusinfieri.com.ar\/?p=455"},"modified":"2023-08-23T20:16:00","modified_gmt":"2023-08-23T23:16:00","slug":"intereses-tasas-de-interes-para-los-danos-y-perjuicios-articulo-768-del-cccn-implicancias-del-caso-garcia-de-la-csjn","status":"publish","type":"post","link":"https:\/\/iusinfieri.com.ar\/index.php\/2023\/08\/23\/intereses-tasas-de-interes-para-los-danos-y-perjuicios-articulo-768-del-cccn-implicancias-del-caso-garcia-de-la-csjn\/","title":{"rendered":"Intereses. Tasas de inter\u00e9s para los da\u00f1os y perjuicios. Art\u00edculo 768 del CCCN. Implicancias del caso \u00abGarc\u00eda\u00bb de la CSJN"},"content":{"rendered":"\n<p><strong>SUMARIO: 1.Introducci\u00f3n. 2. Qu\u00e9 es el inter\u00e9s y para qu\u00e9 sirve. 3. El inter\u00e9s como mecanismo indirecto de recomposici\u00f3n de valor. 4. Tasas de inter\u00e9s y da\u00f1os y perjuicios. 5. La multiplicaci\u00f3n de tasas bancarias. El caso &#8216;Garc\u00eda&#8217; de la CSJN. 6. Conclusiones.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>1. Introducci\u00f3n<\/strong><\/p>\n\n\n\n<p>En este art\u00edculo se explican nociones b\u00e1sicas sobre las tasas de inter\u00e9s y sobre la impropia funci\u00f3n que les toca cumplir como mecanismo indirecto de recomposici\u00f3n de valor. Tambi\u00e9n se desarrolla brevemente la proyecci\u00f3n que tienen las tasas de inter\u00e9s en los procesos de da\u00f1os y perjuicios. Por \u00faltimo, se analizan las implicancias del caso &#8216;Garc\u00eda&#8217; de la CSJN<a href=\"#_edn1\" id=\"_ednref1\">[1]<\/a>, donde la Corte &#8216;prohibi\u00f3&#8217; la multiplicaci\u00f3n de tasas bancarias.<\/p>\n\n\n\n<p><strong>2. Qu\u00e9 es el inter\u00e9s y para qu\u00e9 sirve<\/strong><\/p>\n\n\n\n<p>T\u00edpicamente se ha dicho que el inter\u00e9s es el precio del cr\u00e9dito. Lo que a uno le cuesta que le presten plata. O bien, la otra cara de la moneda, lo que uno gana prest\u00e1ndole plata a otro. Esa definici\u00f3n nos deja impl\u00edcita la funci\u00f3n primaria del inter\u00e9s, que es servir como indicador del precio del cr\u00e9dito. Si la tasa de inter\u00e9s es m\u00e1s alta, el cr\u00e9dito sale m\u00e1s caro. Cuando la tasa es baja, el cr\u00e9dito est\u00e1 m\u00e1s barato.<\/p>\n\n\n\n<p>Las tasas de inter\u00e9s, entre otras clasificaciones, se suelen dividir en activas y pasivas. Las tasas activas son las que cobran los bancos cuando prestan plata a sus clientes. Las tasas pasivas, al contrario, son las que pagan los bancos a los depositantes. Tambi\u00e9n se han clasificado tradicionalmente en tasas positivas y tasas negativas. La tasa de inter\u00e9s es positiva cuando es superior a cero. Y es negativa cuando es menos de cero<a href=\"#_edn2\" id=\"_ednref2\">[2]<\/a>. En un contexto inflacionario como el que soportamos actualmente en nuestro pa\u00eds, no hay ninguna tasa que sea menos de cero. Sin embargo, s\u00ed hay muchas tasas que aun estando por encima del cero y siendo tasas de inter\u00e9s positivas, no alcanzan a mantener el valor del capital porque est\u00e1n por debajo de la inflaci\u00f3n acumulada en un per\u00edodo de tiempo determinado. Esas tasas, si bien son estrictamente positivas, se dice que son tasas reales negativas, justamente por estar debajo del \u00edndice de inflaci\u00f3n. La tasa real positiva ser\u00e1 aquella que est\u00e9 por encima del \u00edndice de inflaci\u00f3n acumulada.<\/p>\n\n\n\n<p>Las dos variables que gravitan con mayor fuerza a la hora de definir la medida de una tasa de inter\u00e9s son el plazo y el riesgo. Cuanto m\u00e1s tiempo me demore en devolverte la plata que me prestaste, m\u00e1s inter\u00e9s te voy a tener que pagar. Y cuanto m\u00e1s tiempo me comprometa a dejar mis ahorros en tu banco, se supone que m\u00e1s inter\u00e9s me vas a tener que pagar por mi dep\u00f3sito. Esa es la variable temporal, el plazo.<\/p>\n\n\n\n<p>El riesgo, la otra variable, es b\u00e1sicamente la posibilidad de no devoluci\u00f3n. A menor garant\u00eda de devoluci\u00f3n, mayor riesgo y mayor inter\u00e9s. Cuando la solvencia est\u00e1 asegurada, hay menos riesgo y el inter\u00e9s es m\u00e1s bajo. Es menor la tasa de inter\u00e9s que le cobra el banco a un cliente que garantiza su deuda con una prenda o una hipoteca, que el inter\u00e9s que cobra el banco a quien no tiene ninguna garant\u00eda para ofrecer. Cuanto m\u00e1s fr\u00e1gil sea la garant\u00eda de devoluci\u00f3n, mayor va a ser la tasa de inter\u00e9s. De la misma manera, es menor la tasa de inter\u00e9s que paga la Reserva Federal de Estados Unidos, que la que paga un banco argentino. Pero tambi\u00e9n es menor la tasa de inter\u00e9s que paga un banco argentino comparada con la que paga la mutual del barrio a sus socios cuando le depositan dinero. Si la tasa es alt\u00edsima es porque el riesgo es alt\u00edsimo. Cuando la limosna es grande, hasta el santo desconf\u00eda.<\/p>\n\n\n\n<p>Otro componente que gravita sensiblemente en la determinaci\u00f3n de la tasa de inter\u00e9s es el riesgo de rentabilidad de la operaci\u00f3n. En la coyuntura actual de nuestro pa\u00eds sobrevienen movimientos bruscos o disruptivos del tipo de cambio, que alteran el valor de la moneda en relaci\u00f3n a otras monedas o a otros precios de referencia de la econom\u00eda. En nuestro caso, esa alteraci\u00f3n acaba siempre o casi siempre en una disminuci\u00f3n del valor del peso. Ante la posibilidad o ante la inminencia de un movimiento disruptivo de ese tipo, mayor ser\u00e1 la tasa de inter\u00e9s que deber\u00e1n pagar los bancos a los depositantes. Porque la renta que espera tener el ahorrista con su dep\u00f3sito, por ejemplo con un plazo fijo, est\u00e1 expuesta y condicionada a la modificaci\u00f3n del tipo de cambio, que la puede desvanecer por completo. Esa exposici\u00f3n har\u00e1 que el banco suba la tasa de inter\u00e9s para tentar a los depositantes, porque es mayor el riesgo al que ellos se exponen con la operaci\u00f3n.<\/p>\n\n\n\n<p>Por \u00faltimo, y ya para terminar con estas explicaciones de tipo econ\u00f3mico, hay otras variables que inciden en la determinaci\u00f3n de la tasa de inter\u00e9s, que tienen que ver con la macroeconom\u00eda y con el uso de la tasa como herramienta de pol\u00edtica monetaria. En esencia, el gobierno -a trav\u00e9s de la autoridad monetaria- sube o baja artificialmente los tipos de inter\u00e9s en funci\u00f3n de sus objetivos de crecimiento econ\u00f3mico, nivel de actividad deseado, y sus niveles de inflaci\u00f3n. En este campo, el aumento de la tasa de inter\u00e9s implica un encarecimiento del cr\u00e9dito que restringe la inversi\u00f3n y reduce el consumo, disminuyendo as\u00ed el nivel de actividad econ\u00f3mica. Esa suba de tasas produce un enfriamiento de la econom\u00eda, que entre otros efectos busca atenuar los niveles de inflaci\u00f3n.<\/p>\n\n\n\n<p>Hasta ac\u00e1 explicamos algunas cuestiones elementales del inter\u00e9s y de su funci\u00f3n principal, que es servir como indicador del precio del cr\u00e9dito. Pero adem\u00e1s de esa funci\u00f3n primaria o principal, el inter\u00e9s tiene una funci\u00f3n secundaria, impropia, que es la de servir como mecanismo indirecto de recomposici\u00f3n de valor.<\/p>\n\n\n\n<p><strong>3. El inter\u00e9s como mecanismo indirecto de recomposici\u00f3n de valor<\/strong><\/p>\n\n\n\n<p>La Argentina padece desde hace m\u00e1s de veinte a\u00f1os la incongruencia de convivir con un contexto inflacionario y de tener que respetar, a la vez, una ley que proh\u00edbe la indexaci\u00f3n de precios y cualquier tipo de actualizaci\u00f3n monetaria. Cuando se prohibi\u00f3 la indexaci\u00f3n en abril de 1991<a href=\"#_edn3\" id=\"_ednref3\">[3]<\/a>, se estableci\u00f3 la paridad de 10.000 australes con un d\u00f3lar americano, que despu\u00e9s se transform\u00f3 en un peso por d\u00f3lar americano. Esa Ley de Convertibilidad del Austral junto con el plan econ\u00f3mico que se implement\u00f3 a comienzos de la d\u00e9cada del 90&#8242; permitieron domar el proceso hiperinflacionario que vivi\u00f3 el pa\u00eds durante los a\u00f1os 1989 y 1990. A partir de all\u00ed y hasta el a\u00f1o 2002 pr\u00e1cticamente no hubo inflaci\u00f3n en la Argentina<a href=\"#_edn4\" id=\"_ednref4\">[4]<\/a>. Se respet\u00f3 la paridad del peso con el d\u00f3lar, y nadie se enter\u00f3 de que estaba prohibido indexar precios y costos, porque hab\u00eda estabilidad econ\u00f3mica y nadie necesitaba indexar ni actualizar nada. Los precios de la econom\u00eda no cambiaban cada quince o treinta d\u00edas como pasa ahora.<\/p>\n\n\n\n<p>El romance termin\u00f3 con la crisis del a\u00f1o 2001, el quiebre de la paridad cambiaria y la posterior devaluaci\u00f3n del peso contra el d\u00f3lar, que dio comienzo a un proceso inflacionario del que todav\u00eda no hemos salido, que por momentos parece aplacarse, y por otros momentos parece agravarse. En este contexto inflacionario, esa misma prohibici\u00f3n de indexar que casi no nos trajo ning\u00fan problema en tiempos de estabilidad cambiaria, hoy resulta una verdadera piedra en el zapato para cualquier ciudadano, ya sea comerciante, consumidor, inquilino, locador, empresario, ni hablar los contadores, abogados, y cualquiera que quiera emprender y calcular los costos de una inversi\u00f3n y la rentabilidad esperada.<\/p>\n\n\n\n<p>En tiempos de estabilidad econ\u00f3mica la prohibici\u00f3n de indexar pas\u00f3 pr\u00e1cticamente desapercibida. En tiempos de alta inflaci\u00f3n cruje por los cuatro costados. Aun as\u00ed, la decisi\u00f3n de los sucesivos gobiernos y de la propia Corte de la Naci\u00f3n fue de mantener la prohibici\u00f3n de indexar<a href=\"#_edn5\" id=\"_ednref5\">[5]<\/a>. Los motivos de esa decisi\u00f3n son variados y se pueden compartir o no, pero no vienen al caso en este art\u00edculo<a href=\"#_edn6\" id=\"_ednref6\">[6]<\/a>. La indexaci\u00f3n y la actualizaci\u00f3n monetaria siguen prohibidas y hay que convivir con esa prohibici\u00f3n. Y para sobrellevar esa convivencia, doctrina y jurisprudencia han ido habilitando una serie de mecanismos indirectos de recomposici\u00f3n de valor, que sin ser estrictamente una indexaci\u00f3n, permiten restituir el valor que se pierde con la nominalidad en un contexto inflacionario, y a la vez esquivan esa prohibici\u00f3n legal de indexar<a href=\"#_edn7\" id=\"_ednref7\">[7]<\/a>.<\/p>\n\n\n\n<p>Entre esos mecanismos indirectos de recomposici\u00f3n de valor se incluye el inter\u00e9s, que adem\u00e1s de cumplir su funci\u00f3n primaria de servir como precio del dinero o del cr\u00e9dito, cumple ahora la impropia funci\u00f3n de recomponer el valor del capital<a href=\"#_edn8\" id=\"_ednref8\">[8]<\/a>. O sea que se agrega al inter\u00e9s un componente m\u00e1s, adem\u00e1s de aquel componente natural de representar el precio del cr\u00e9dito, ahora se agrega la recomposici\u00f3n de valor. L\u00f3gicamente, la medida de esa recomposici\u00f3n de valor debe determinarse en funci\u00f3n de la p\u00e9rdida de valor sufrida. Esto es algo que suena bastante elemental, pero vale la pena aclararlo.<\/p>\n\n\n\n<p>En este caso, la medida de este componente del inter\u00e9s no va a depender del plazo ni del riesgo de devoluci\u00f3n, ni tampoco del riesgo de rentabilidad que suponga la operaci\u00f3n. Ac\u00e1 es distinto, es mucho m\u00e1s f\u00e1cil. Una tasa de inter\u00e9s va a cumplir satisfactoriamente su funci\u00f3n de recomposici\u00f3n de valor cuando recupere exactamente el mismo valor que se perdi\u00f3 en un per\u00edodo de tiempo determinado por efecto de la desvalorizaci\u00f3n monetaria. Y la forma com\u00fanmente admitida para medir esa desvalorizaci\u00f3n es a trav\u00e9s del \u00cdndice de Precios al Consumidor que publica el INDEC<a href=\"#_edn9\" id=\"_ednref9\">[9]<\/a>. O sea que para definir la medida de este componente habr\u00eda que computar la inflaci\u00f3n acumulada durante el per\u00edodo de tiempo que se analiza, y aplicar un inter\u00e9s que recomponga \u00edntegramente ese valor perdido por efecto de la desvalorizaci\u00f3n monetaria. As\u00ed se habr\u00e1 cumplido en forma perfecta esta funci\u00f3n de recomposici\u00f3n de valor que le toca cumplir al inter\u00e9s. Y a eso habr\u00e1 que agregarle, luego, el precio del cr\u00e9dito en funci\u00f3n de las variables que expusimos en el punto anterior (plazo, riesgo, etc.).<\/p>\n\n\n\n<p>Si la medida de la tasa de inter\u00e9s no alcanza a recomponer \u00edntegramente el valor perdido por efecto de la desvalorizaci\u00f3n monetaria, vamos a estar frente a una tasa de inter\u00e9s real negativa. Si, al contrario, la tasa de inter\u00e9s est\u00e1 por encima de la inflaci\u00f3n acumulada, estaremos frente a una tasa de inter\u00e9s real positiva. Cuando la tasa de inter\u00e9s real es negativa, al deudor le conviene no pagar. Porque a medida que pasa el tiempo el valor de su deuda disminuye. Cuando la tasa de inter\u00e9s real es positiva, el deudor est\u00e1 compelido a pagar, porque a medida que pasa el tiempo el valor de su deuda aumenta.<\/p>\n\n\n\n<p>En la actualidad, todas las tasas de inter\u00e9s bancarias, con mayor o menor \u00e9xito y m\u00e1s all\u00e1 de que sean tasas de inter\u00e9s real positivas o negativas, contienen un componente de recomposici\u00f3n de valor. A diferencia de las que se denominan tasas de inter\u00e9s puras, que se expresan en t\u00e9rminos nominales, como por ejemplo del 6 u 8% anual, que en principio se puede decir que s\u00f3lo obedecen al precio del cr\u00e9dito y no recomponen valor.<\/p>\n\n\n\n<p>Despu\u00e9s de estas nociones b\u00e1sicas sobre el inter\u00e9s, pasemos ahora al tema que nos convoca, que es la tasa de inter\u00e9s en los juicios de da\u00f1os y perjuicios, y las implicancias que ha tenido el precedente &#8216;Garc\u00eda&#8217; de la CSJN.<\/p>\n\n\n\n<p><strong>4. Tasas de inter\u00e9s y da\u00f1os y perjuicios<\/strong><\/p>\n\n\n\n<p>Las tasas de inter\u00e9s en el marco de los da\u00f1os y perjuicios han sido objeto de un extenso debate<a href=\"#_edn10\" id=\"_ednref10\">[10]<\/a>. Se ha discutido pr\u00e1cticamente todo. Si la tasa debe ser pura o bancaria. Si es bancaria, si tiene que ser activa o pasiva<a href=\"#_edn11\" id=\"_ednref11\">[11]<\/a>. Si es activa, si se puede capitalizar o no. Si la tasa de inter\u00e9s hay que aplicarla desde la fecha del hecho, desde la demanda o desde la sentencia. Si es desde la sentencia, si se aplica desde la fecha del dictado de la sentencia o desde la fecha en que qued\u00f3 firme la sentencia<a href=\"#_edn12\" id=\"_ednref12\">[12]<\/a>. En fin, se discuti\u00f3 de todo y no viene al caso reeditar todos esos debates porque responden a coyunturas econ\u00f3micas pasadas, que poco tienen que ver con la realidad actual.<\/p>\n\n\n\n<p>S\u00ed nos interesa dejar bien en claro que quien debe una indemnizaci\u00f3n por da\u00f1os y perjuicios est\u00e1 en mora desde la misma fecha del hecho en que produjo el da\u00f1o. Y desde ese mismo momento el deudor debe compensar a la v\u00edctima por la indisposici\u00f3n del capital que le debe. Por eso es que a la indemnizaci\u00f3n de los da\u00f1os y perjuicios le accede un inter\u00e9s moratorio que compensa todo ese tiempo durante el cual la v\u00edctima no pudo disponer libremente del capital que le correspond\u00eda. En l\u00ednea con ello, el art\u00edculo 1748 del C.C.C.N. prev\u00e9 que &#8216;el curso de los intereses comienza desde que se produce cada perjuicio&#8217;.<\/p>\n\n\n\n<p>Usualmente se dice que la v\u00edctima de da\u00f1os y perjuicios es acreedora de una deuda de valor. Es decir, no le deben un monto expresado nominalmente, sino un valor determinado, que por lo general se cuantifica cuando es reconocido en la sentencia, y reci\u00e9n all\u00ed se expresa en t\u00e9rminos nominales, y pasa a ser una obligaci\u00f3n de dar dinero, conforme lo prescribe el art\u00edculo 772 del C.C.C.N. De modo que la indemnizaci\u00f3n se fija, como se suele decir, &#8216;a valores actuales&#8217;. Es el t\u00edpico caso, por ejemplo, de la indemnizaci\u00f3n por incapacidad sobreviniente, donde el juez toma los puntos de incapacidad que surgen de la prueba de la causa y les atribuye un monto en dinero. Ese monto por cada punto de incapacidad suele ser consensuado entre los distintos tribunales del fuero, y se va actualizando cada cuatro o cinco meses. Lo mismo sucede con el da\u00f1o moral. El juez lo suele fijar en el momento de dictar la sentencia. Tambi\u00e9n, por ejemplo, la indemnizaci\u00f3n por privaci\u00f3n de uso del rodado. Suele haber un monto de consenso de cu\u00e1nto cuesta sobrellevar un d\u00eda sin un veh\u00edculo, y ese monto se va actualizando peri\u00f3dicamente.<\/p>\n\n\n\n<p>Todos esos rubros se estiman &#8216;a valores actuales&#8217;, y muchas veces difieren sustancialmente de los reclamados nominalmente por el actor en su demanda. Esto puede llegar a interpretarse como un quiebre en la congruencia aritm\u00e9tica entre lo pretendido en la demanda y lo concedido por el tribunal en la sentencia. Pero en realidad se trata de una soluci\u00f3n necesaria en el contexto inflacionario actual, e indispensable para no afectar el derecho constitucional de la v\u00edctima a una reparaci\u00f3n plena. Adem\u00e1s, la tarea de cuantificar y expresar en t\u00e9rminos nominales el valor de los da\u00f1os es propia del juez al momento de fallar. Y la cuantificaci\u00f3n de los da\u00f1os, por otra parte, se suele dejar librada &#8216;a lo que en m\u00e1s o en menos surja de la prueba de la causa o del buen criterio del tribunal&#8217;. De manera que no hay en absoluto un quiebre en la congruencia.<\/p>\n\n\n\n<p>Ahora bien, no necesariamente todos los rubros de un reclamo por da\u00f1os y perjuicios van a ser cuantificados &#8216;a valores actuales&#8217; en la sentencia. Hay rubros que convenientemente se indemnizan &#8216;a valores hist\u00f3ricos&#8217;. Tal es el caso, por ejemplo, del da\u00f1o material sobre el rodado, cuya medida usualmente se acredita con el presupuesto de reparaci\u00f3n de un taller mec\u00e1nico o con el recibo de pago del taller por haber realizado esa reparaci\u00f3n. Este rubro se suele reconocer en la sentencia al mismo monto nominal que se pag\u00f3 en su oportunidad. Ser\u00eda un verdadero incordio para el juez actualizar a la fecha de la sentencia el valor de cada autoparte que se reemplaz\u00f3, y calcular el valor actual de la mano de obra que insumi\u00f3 la reparaci\u00f3n. Lo mismo si en lugar de ese presupuesto de reparaci\u00f3n del taller mec\u00e1nico se produjo en la causa una prueba pericial mec\u00e1nica para determinar el costo de los da\u00f1os. En este caso es el perito el que expresa nominalmente el costo de la reparaci\u00f3n. El juez va a asumir ese monto nominal a valor hist\u00f3rico (al momento del peritaje), sin actualizarlo en el momento de la sentencia.<\/p>\n\n\n\n<p>Vemos entonces que en da\u00f1os y perjuicios nos vamos a encontrar, b\u00e1sicamente, con dos posibilidades. O bien que el monto de la indemnizaci\u00f3n se fije al momento en que el juez dicta el pronunciamiento, lo que com\u00fanmente se dice &#8216;a valores actuales&#8217;. O bien que se condene a pagar alguna suma de dinero que se haya estimado nominalmente antes de la sentencia (por ejemplo en la demanda, o en el peritaje), &#8216;a valores hist\u00f3ricos&#8217;.<\/p>\n\n\n\n<p>La fecha en que un rubro se expresa en t\u00e9rminos nominales es de vital importancia para la elecci\u00f3n de la tasa de inter\u00e9s. Ese momento de expresi\u00f3n de la nominalidad implica que a partir de all\u00ed la indemnizaci\u00f3n va a estar afectada por el proceso de desvalorizaci\u00f3n monetaria. Y va a ser justamente a partir de ese momento (y no antes) que se debe aplicar una tasa de inter\u00e9s que, adem\u00e1s de servir como precio del dinero, cumpla tambi\u00e9n con la impropia funci\u00f3n de recomponer el valor, para que la indemnizaci\u00f3n no se diluya por efecto de la inflaci\u00f3n. Como ya dijimos, son las tasas bancarias y no las tasas puras las que contienen ese segundo componente de recomposici\u00f3n de valor del capital.<\/p>\n\n\n\n<p>Entonces, para responder al interrogante de cu\u00e1ndo debe el juez aplicar una tasa de inter\u00e9s bancaria que recomponga valor, es necesario indagar en qu\u00e9 momento se expres\u00f3 en t\u00e9rminos nominales el rubro que se indemniza. Ese momento en que se expres\u00f3 la nominalidad es el que define cu\u00e1ndo hay que aplicar una tasa bancaria, y puede diferir respecto de cada uno de los distintos rubros indemnizatorios. En algunos casos puede ser la sentencia, en otros la demanda, en otros el peritaje, etc. Todo va a depender, repetimos, del momento en que se expresa la nominalidad. Para cada rubro ese puede ser un momento distinto, que deber\u00e1 computar debidamente el juez para hacer las distinciones correspondientes en la aplicaci\u00f3n de la tasa.<\/p>\n\n\n\n<p>Sabemos entonces que la tasa bancaria se va a aplicar reci\u00e9n a partir del momento en que se expresa la nominalidad. Cabe ahora preguntarse qu\u00e9 tasa se debe aplicar desde la fecha de la mora hasta ese momento posterior en que la acreencia se expresa en t\u00e9rminos nominales y se le aplica una tasa de inter\u00e9s bancaria. Durante todo ese tiempo el deudor ya estaba en mora. Recordemos que en los da\u00f1os y perjuicios el responsable est\u00e1 en mora desde la misma fecha del hecho que produce el da\u00f1o. Pero en este caso, el inter\u00e9s no va a necesitar un componente de recomposici\u00f3n de valor, porque hasta la fecha en que se expresa en t\u00e9rminos nominales, la acreencia no se ve afectada por la desvalorizaci\u00f3n de la moneda. Por eso se debe aplicar durante ese per\u00edodo una tasa de inter\u00e9s que cumpla la sola funci\u00f3n de servir como precio del dinero, sin aquel componente de recomposici\u00f3n de valor que tienen las tasas bancarias. Para eso se aplica una tasa pura, ya sea del orden del 6 o del 8% anual, desde la fecha del hecho y hasta la fecha en que se expres\u00f3 la nominalidad<a href=\"#_edn13\" id=\"_ednref13\">[13]<\/a>. A partir de all\u00ed s\u00ed, la tasa bancaria.<\/p>\n\n\n\n<p>Hasta ac\u00e1 explicamos cuestiones b\u00e1sicas sobre las tasas de inter\u00e9s y su proyecci\u00f3n en el \u00e1mbito de los da\u00f1os y perjuicios. Si bien se trata de aspectos ciertamente elementales de esta materia, consideramos que viene bien refrescarlos, porque la prohibici\u00f3n legal de indexar ha conducido la cuesti\u00f3n de los intereses por senderos de relativa oscuridad. Las palabras &#8216;actualizaci\u00f3n&#8217;, &#8216;recomposici\u00f3n de valor&#8217;, &#8216;inflaci\u00f3n&#8217;, y otras similares parecen haber quedado afuera del diccionario, ensombreciendo as\u00ed cualquier reflexi\u00f3n sincera sobre el tema. La tarea de recomposici\u00f3n de valor que le toca cumplir a la tasa de inter\u00e9s se ha escondido detr\u00e1s de escena, procurando a toda costa evitar caer en la indexaci\u00f3n. Eso ha impedido que la cuesti\u00f3n se aborde con la precisi\u00f3n y la honestidad que merece.<\/p>\n\n\n\n<p>Pasemos ahora s\u00ed a la novedad. Vamos a analizar el caso &#8216;Garc\u00eda&#8217;<a href=\"#_edn14\" id=\"_ednref14\">[14]<\/a> de la Corte Suprema de Justicia de la Naci\u00f3n, donde la Corte &#8216;prohibi\u00f3&#8217; el mecanismo de multiplicaci\u00f3n de tasas bancarias al que echaban mano buena parte de los tribunales del pa\u00eds buscando una tasa de inter\u00e9s que cumpliera satisfactoriamente la doble funci\u00f3n de recomponer el valor, por un lado, y de servir como precio por el uso del dinero, por el otro.<\/p>\n\n\n\n<p><strong>5. La multiplicaci\u00f3n de tasas bancarias. El caso &#8216;Garc\u00eda&#8217; de la CSJN<\/strong><\/p>\n\n\n\n<p>Los vaivenes de la econom\u00eda, el aumento de la inflaci\u00f3n, y la pol\u00edtica de tasas del Banco Central de los \u00faltimos a\u00f1os han hecho que muchas tasas de inter\u00e9s bancarias que eran antes tasas de inter\u00e9s real positivas, se hayan convertido en tasas de inter\u00e9s real negativas. Recordemos que la tasa tiene un inter\u00e9s real positivo cuando recompone \u00edntegramente el valor de una suma expresada en t\u00e9rminos nominales. Y es negativa cuando no alcanza a recomponer ese valor.<\/p>\n\n\n\n<p>Entonces, por ejemplo, la tasa activa sumada del Banco Naci\u00f3n para descontar un documento a treinta d\u00edas supo estar por encima del \u00edndice de inflaci\u00f3n, constituyendo as\u00ed una tasa de inter\u00e9s real positiva. Si hoy se mide esa misma tasa a\u00f1o contra a\u00f1o (desde el 1\/8\/23 hasta el 1\/8\/22) nos da un coeficiente de 1,872, es decir un inter\u00e9s anual aproximado del 83%, contra una inflaci\u00f3n acumulada de 113,4% en el mismo per\u00edodo. La tasa est\u00e1 por debajo de la inflaci\u00f3n acumulada. O sea que hoy la tasa activa sumada del Banco Naci\u00f3n es una tasa de inter\u00e9s real negativa.<\/p>\n\n\n\n<p>La tasa negativa, esto vale la pena recalcarlo, no cumple ninguna de las dos funciones que antes describimos. No recompone el valor, porque est\u00e1 por debajo del \u00edndice de inflaci\u00f3n acumulada, y l\u00f3gicamente tampoco alcanza para servir como precio del cr\u00e9dito. Es decir, no cumple -o cumple muy mal- las dos funciones que se le asignan.<\/p>\n\n\n\n<p>En virtud de este fen\u00f3meno en que las tasas positivas pasaron a ser tasas reales negativas, los tribunales comenzaron a multiplicar las tasas bancarias para establecer intereses que verdaderamente cumplieran esa doble funci\u00f3n. Fue as\u00ed que, por ejemplo, en lugar de aplicar la tasa activa sumada del Banco Naci\u00f3n para descontar documentos a treinta d\u00edas, pasaron a aplicar una vez y media esa misma tasa. La multiplicaban por 1,5. Hoy esa cuenta arroja un coeficiente de 2,307 (08\/23 contra 08\/22), o sea un inter\u00e9s del 123% anual. Ah\u00ed s\u00ed la tasa est\u00e1 por encima de la inflaci\u00f3n acumulada y por ende recompone \u00edntegramente el valor de la acreencia, y tiene adem\u00e1s un extra que corresponde al segundo componente (cercano al 8% anual), de compensaci\u00f3n por el uso del dinero.<\/p>\n\n\n\n<p>En el caso de la Provincia de Santa Fe, por ejemplo, la tasa activa sumada para descuento de documentos a treinta d\u00edas del Nuevo Banco de Santa Fe es una tasa real negativa. Si uno compara a\u00f1o contra a\u00f1o (08\/23 contra 08\/22) nos da un coeficiente de 1,442, un inter\u00e9s del 44% anual aproximado, contra una inflaci\u00f3n del 113,4% anual durante el mismo per\u00edodo. Est\u00e1 muy por debajo del \u00edndice de inflaci\u00f3n. Si uno multiplica esa tasa por 1,5, es decir si aplica una vez y media esa tasa, nos da un inter\u00e9s del 66% anual aproximado. Sigue siendo una tasa real negativa que no compensa la desvalorizaci\u00f3n monetaria. Y si uno la multiplica por dos, es decir si aplica dos veces la tasa activa sumada para descuento de documentos a treinta d\u00edas del Nuevo Banco de Santa Fe, eso nos da un inter\u00e9s del 88% anual aproximado. Todav\u00eda est\u00e1 muy por debajo de la inflaci\u00f3n acumulada. No recompone el valor, no compensa el uso del dinero y -muy importante- no alienta a que el deudor pague.<\/p>\n\n\n\n<p>La cuesti\u00f3n es que con mayor o menor \u00e9xito, los tribunales echaron mano al mecanismo de multiplicar las tasas de inter\u00e9s bancarias para conseguir o al menos para acercarse a un inter\u00e9s que verdaderamente recompusiera el valor del capital y a la vez compensara el uso del dinero. Y ese mecanismo de multiplicaci\u00f3n es justamente lo que acaba de condenar la Corte en el caso \u201cGarc\u00eda, Javier Omar c\/ UGOFE SA y otros s\/ da\u00f1os y perjuicios\u201d.<\/p>\n\n\n\n<p>La raz\u00f3n que dio la Corte para prohibir esa multiplicaci\u00f3n de la tasa es que el art\u00edculo 768 del C.C.C.N. establece que la tasa de inter\u00e9s se debe determinar por lo que acuerden las partes (A), o por lo que dispongan las leyes especiales (B), o en subsidio por tasas que se fijen seg\u00fan las reglamentaciones del Banco Central (C). Y el Banco Central no regula tasas multiplicadas a la manera de una vez y media o dos veces una tasa. Por eso la Corte juzg\u00f3 que ese mecanismo de multiplicaci\u00f3n implica un apartamiento del inciso tercero del art\u00edculo 768, porque una tasa multiplicada no es una tasa fijada &#8216;seg\u00fan las reglamentaciones del Banco Central&#8217;.<\/p>\n\n\n\n<p>De acuerdo al dictamen del procurador fiscal que la Corte hizo suyo, la Sala H de la C\u00e1mara Nacional de Apelaciones en lo Civil hab\u00eda aplicado intereses en un juicio de da\u00f1os y perjuicios a la &#8216;tasa activa cartera general nominal anual vencida a treinta d\u00edas del Banco de la Naci\u00f3n Argentina&#8217; desde la fecha del accidente y hasta el 1\/8\/15, y a partir de esa fecha duplic\u00f3 esa tasa hasta el efectivo pago.<\/p>\n\n\n\n<p>El procurador descalific\u00f3 el fallo de la c\u00e1mara por una raz\u00f3n de congruencia procesal. Dijo que la pretensi\u00f3n del actor ante la alzada hab\u00eda sido solamente la modificaci\u00f3n de la tasa pasiva que hab\u00eda fijado el juez de primera instancia desde la fecha del accidente y hasta la fecha de su sentencia, y en su lugar pidi\u00f3 que se aplique una tasa activa. La c\u00e1mara, adem\u00e1s de hacer lugar a esa pretensi\u00f3n apelatoria, duplic\u00f3 la tasa activa desde el 1\/8\/15 y hasta el efectivo pago. El procurador sostuvo que esa duplicaci\u00f3n hab\u00eda excedido la medida del agravio.<\/p>\n\n\n\n<p>Hasta ah\u00ed todo fant\u00e1stico. Porque si se asume como v\u00e1lido el escenario que expone el procurador en su dictamen, est\u00e1 muy clara la extralimitaci\u00f3n de la Sala H de la C\u00e1mara Nacional Civil. Bien se sabe que el agravio es la medida del recurso. Y la c\u00e1mara no puede dar al apelante m\u00e1s de lo que pidi\u00f3 en sus agravios. Ese vicio hace que el fallo de la c\u00e1mara sea arbitrario y que deba ser anulado por la Corte.<\/p>\n\n\n\n<p>Pero lo controvertido y novedoso de este pronunciamiento no est\u00e1 en el dictamen del procurador, que se sustenta en doctrina y jurisprudencia conocidas, sino en los fundamentos que incorpor\u00f3 la Corte en su considerando tercero: \u201cla multiplicaci\u00f3n de una tasa de inter\u00e9s -en este caso, al aplicar &#8216;doble tasa activa&#8217;- a partir del 1\u00b0 de agosto de 2015, resulta en una tasa que no ha sido fijada seg\u00fan las reglamentaciones del Banco Central, por lo que contrariamente a lo que afirma el tribunal a quo, la decisi\u00f3n no se ajusta a los criterios previstos por el legislador en el mencionado art. 768 del C\u00f3digo Civil y Comercial de la Naci\u00f3n\u201d. Con toda claridad la Corte expres\u00f3 que la multiplicaci\u00f3n de tasas no es un mecanismo habilitado por el legislador. O sea que no est\u00e1 permitido a los jueces multiplicar las tasas de inter\u00e9s. O por lo menos, no deber\u00edan hacerlo sin declarar la inconstitucionalidad de la norma.<\/p>\n\n\n\n<p>La primera reflexi\u00f3n que creo que hay que hacer sobre este fallo es que la descalificaci\u00f3n que hizo la Corte de la tasa activa duplicada del Banco Naci\u00f3n se sustent\u00f3 en razones formales y no sustanciales. Una descalificaci\u00f3n sustancial de la tasa de inter\u00e9s ser\u00eda a mi criterio aquella que analiza en t\u00e9rminos aritm\u00e9ticos el \u00e9xito o fracaso de la tasa en el cumplimiento de su doble funci\u00f3n de servir como compensaci\u00f3n por el uso del dinero y de servir, tambi\u00e9n, como mecanismo indirecto de recomposici\u00f3n de valor. Si la tasa no cumple esas funciones o las cumple mal, eso necesariamente se traduce en una afectaci\u00f3n del derecho de propiedad de alguna de las partes, que est\u00e1 protegido por el art\u00edculo 17 de la Constituci\u00f3n Nacional. Esa afectaci\u00f3n al derecho constitucional de propiedad es lo que permitir\u00eda descalificar la tasa de inter\u00e9s en t\u00e9rminos sustanciales. En los casos de da\u00f1os y perjuicios, adem\u00e1s, el incumplimiento de esa doble funci\u00f3n afectar\u00eda el derecho a una reparaci\u00f3n plena del da\u00f1o, en los t\u00e9rminos en que lo prescribe el art\u00edculo 1740 del C.C.C.N., con anclaje en el art\u00edculo 19 de la Constituci\u00f3n Nacional.<\/p>\n\n\n\n<p>El cumplimiento de la funci\u00f3n de recomponer el valor es el m\u00e1s f\u00e1cil de medir. Ya lo explicamos. Hay que tomar la inflaci\u00f3n acumulada durante el mismo per\u00edodo en que se aplica la tasa de inter\u00e9s, y corroborar si con la tasa se alcanza a recomponer el 100% de la p\u00e9rdida de valor. Esto se puede medir en t\u00e9rminos exactos, con decimales y todo. La funci\u00f3n de compensar el uso del dinero es m\u00e1s discrecional. El precio del cr\u00e9dito responde a muchas variables que ya hemos resumido y que no viene al caso reiterar ahora. Pero por consenso se suele considerar que el precio del cr\u00e9dito se ubica entre un 6% y un 8% anual, y as\u00ed lo entienden la mayor\u00eda de los tribunales del pa\u00eds. As\u00ed que nos quedamos con esos n\u00fameros.<\/p>\n\n\n\n<p>En el fallo de la Corte no se hizo este an\u00e1lisis para averiguar si la duplicaci\u00f3n de la tasa activa del Banco Naci\u00f3n se traduc\u00eda o no en una afectaci\u00f3n al derecho de propiedad de la v\u00edctima o del demandado. Por eso es que consideramos que la descalificaci\u00f3n del pronunciamiento no fue por una raz\u00f3n sustancial sino por una raz\u00f3n formal. Ahora bien, vamos a hacer ahora ese an\u00e1lisis sustancial de la tasa de inter\u00e9s que no hizo (o al menos no explicit\u00f3) la Corte, para ver si hab\u00eda o no una verdadera afectaci\u00f3n sustancial del derecho. Vale antes la aclaraci\u00f3n de que el recurso de queja ante la Corte lo interpuso la demandada UGOFE SA. Por lo que se supone que si la Corte hizo lugar al recurso es porque la duplicaci\u00f3n de la tasa perjudicaba en alguna medida a la demandada recurrente. Vamos a ver.<\/p>\n\n\n\n<p>El reproche del m\u00e1ximo tribunal se concentr\u00f3 en la aplicaci\u00f3n del doble de la tasa activa del Banco Naci\u00f3n desde el 1\/8\/15 y hasta el efectivo pago. La sentencia de la Corte es del 7 de marzo de 2023. Durante ese per\u00edodo (1\/8\/15 al 7\/3\/23) la aplicaci\u00f3n del doble de la tasa activa del Banco Naci\u00f3n arrojaba un coeficiente de 7,315. O sea que si el demandado deb\u00eda $ 100 el 1\/8\/15, el d\u00eda en que fall\u00f3 la Corte iba a deber $ 731,50 con esa tasa activa duplicada. Es un inter\u00e9s total del 631,50% aproximadamente.<\/p>\n\n\n\n<p>En ese mismo per\u00edodo de tiempo, entre el mes de agosto del 2015 y el mes de marzo de 2023, la inflaci\u00f3n acumulada fue casi del 1.900% (las calculadoras de inflaci\u00f3n oscilan entre el 1.600% y el 2.000%, por raz\u00f3n de que algunos meses no hubo estad\u00edsticas oficiales precisas). O sea que si la demandada UGOFE SA deb\u00eda $ 100 el 1\/8\/15, para que el valor de su deuda se mantuviera constante hasta el d\u00eda en que fall\u00f3 la Corte, su deuda actualizada tendr\u00eda que haber sido de $ 1.900 aproximadamente. Y con la tasa que aplicaba la c\u00e1mara resultaba ser de $ 731,50. Esto quiere decir que la tasa que hab\u00eda aplicado la c\u00e1mara de apelaciones beneficiaba groseramente a la demandada UGOFE SA, a la vez que perjudicaba al actor Javier Garc\u00eda, vulnerando sus derechos constitucionales de propiedad y de acceso a una reparaci\u00f3n plena. Aun as\u00ed, siendo la gran beneficiada, la demandada cuestion\u00f3 la tasa, fue en queja ante la Corte, y aun as\u00ed gan\u00f3. Si uno analiza el pronunciamiento desde este punto de vista (que considero el m\u00e1s importante), el fallo resulta verdaderamente parad\u00f3jico y contrario a toda l\u00f3gica.<\/p>\n\n\n\n<p>Pero bueno, es verdad que el art\u00edculo 768 del C\u00f3digo Civil y Comercial habla de tasas fijadas seg\u00fan las reglamentaciones del Banco Central, y posiblemente la multiplicaci\u00f3n de tasas no est\u00e9 estrictamente dentro de esas reglamentaciones<a href=\"#_edn15\" id=\"_ednref15\">[15]<\/a> si uno asume una interpretaci\u00f3n restrictiva del art\u00edculo. Pero aqu\u00ed parece haberse subordinado la sustancia al rito, contradiciendo la reconocida postura que tradicionalmente ha asumido la Corte<a href=\"#_edn16\" id=\"_ednref16\">[16]<\/a>. El hecho de que la tasa duplicada del Banco Naci\u00f3n no est\u00e9 reglamentada por el BCRA es mucho menos importante que el hecho de que se licue la indemnizaci\u00f3n y de que se vulnere el derecho de la v\u00edctima a una reparaci\u00f3n plena. Es algo bastante evidente que el derecho constitucional a la reparaci\u00f3n plena del da\u00f1o y el derecho constitucional de propiedad tienen mayor jerarqu\u00eda que la pauta reglamentaria del inciso C del art\u00edculo 768 del C\u00f3digo Civil y Comercial, a la que no se le puede atribuir un verdadero anclaje constitucional.<\/p>\n\n\n\n<p>La interpretaci\u00f3n restrictiva del art\u00edculo 768 inciso C que hizo el m\u00e1ximo tribunal circunscribiendo las tasas de inter\u00e9s estricta y excluyentemente a las que se fijen &#8216;seg\u00fan las reglamentaciones del Banco Central&#8217;, acab\u00f3 consagrando una flagrante injusticia para la v\u00edctima, que ya padec\u00eda una tasa de inter\u00e9s baja, y acabar\u00e1 sin dudas con una tasa de inter\u00e9s todav\u00eda m\u00e1s baja.<\/p>\n\n\n\n<p>Lo que llama poderosamente la atenci\u00f3n es que esa interpretaci\u00f3n estricta y excluyente de la norma contradice los propios fundamentos que explicit\u00f3 el legislador al sancionarla, cuando dijo que \u201chay supuestos de hecho muy diversos y es necesario disponer de mayor flexibilidad a fin de adoptar la soluci\u00f3n m\u00e1s justa para el caso.\u201d<a href=\"#_edn17\" id=\"_ednref17\">[17]<\/a>. Justamente cuando los tribunales acuden a la multiplicaci\u00f3n de tasas &#8216;a fin de adoptar la soluci\u00f3n m\u00e1s justa para el caso&#8217;, en lugar de reconocer la flexibilidad de la materia, la Corte responde con rigidez. Es una verdadera contradicci\u00f3n, y ha dejado perplejos a buena parte de los jueces, que ya no podr\u00e1n utilizar la herramienta de multiplicaci\u00f3n de tasas para hacer justicia en el caso concreto, como lo ven\u00edan haciendo hasta ahora.<\/p>\n\n\n\n<p>Y ya que estamos nos podemos preguntar hasta qu\u00e9 punto la Corte piensa restringir la interpretaci\u00f3n del inciso C del art\u00edculo 768 del C.C.C.N. \u00bfAcaso la tasa de inter\u00e9s pura del 6% anual o del 8% anual que la mayor\u00eda de los tribunales del pa\u00eds aplican como inter\u00e9s moratorio en las deudas de valor es una tasa fijada &#8216;seg\u00fan las reglamentaciones del Banco Central&#8217;? Pareciera que no, no lo es<a href=\"#_edn18\" id=\"_ednref18\">[18]<\/a>. \u00bfTambi\u00e9n hay que declarar la inconstitucionalidad del 768 inciso C para aplicar esa tasa pura? Esperemos que no.<\/p>\n\n\n\n<p>En definitiva, el fallo de la Corte no abunda en razones sustanciales, sino m\u00e1s bien formales o superficiales. Es dif\u00edcil comprender cu\u00e1l es el verdadero sentido detr\u00e1s de este pronunciamiento, si es que lo hay. De lo que s\u00ed hay certeza es de que el resultado final no ha sido justo para la v\u00edctima.<\/p>\n\n\n\n<p>Hay algo que debe quedar bien claro. Con la tasa de inter\u00e9s no se deber\u00eda ni beneficiar al acreedor ni aliviar al deudor (desproporcionadamente). En cualquier escenario en que la tasa de inter\u00e9s implique un beneficio injustificado para alguna de las partes en disputa y un consecuente perjuicio para la otra, habr\u00e1 una afectaci\u00f3n ileg\u00edtima del derecho constitucional de propiedad y habr\u00e1 arbitrariedad. Y vale la aclaraci\u00f3n entre par\u00e9ntesis, &#8216;desproporcionadamente&#8217;, porque es una verdadera constante el favor que reciben los deudores de parte de los tribunales de justicia a trav\u00e9s de la aplicaci\u00f3n de tasas de inter\u00e9s que no alcanzan a cumplir la funci\u00f3n de recomposici\u00f3n del valor del capital.<\/p>\n\n\n\n<p>Es decir, en la pr\u00e1ctica se aplican recurrentemente tasas reales negativas que benefician a los deudores. Y ese <em>favor debitoris<\/em> nunca es explicitado ni justificado por el sentenciante, sino que est\u00e1 encubierto en una tasa de inter\u00e9s cuya elecci\u00f3n suele tener muy pocas explicaciones y, consecuentemente, muy pocas posibilidades de contradicci\u00f3n recursiva. Adem\u00e1s, parad\u00f3jicamente, los deudores que ahora se benefician a costa de las v\u00edctimas no suelen ser los deudores vulnerables que hist\u00f3ricamente se ha buscado proteger con el <em>favor debitoris<\/em>. Al contrario, son los proveedores, las aseguradoras, las grandes empresas, los empleadores, etc.<\/p>\n\n\n\n<p>En escenarios de alta inflaci\u00f3n como el que vivimos actualmente, la tasa de inter\u00e9s tiene una funci\u00f3n important\u00edsima para asegurar la atribuci\u00f3n de derechos que se hace en la sentencia. De poco vale el reconocimiento de un derecho si el acreedor lo percibe completamente licuado cuando lo va a cobrar<a href=\"#_edn19\" id=\"_ednref19\">[19]<\/a>. Una mala elecci\u00f3n de la tasa de inter\u00e9s puede alterar sustancialmente la atribuci\u00f3n de derechos del fallo. Por eso hay que poner especial cuidado en la elecci\u00f3n de la tasa, detr\u00e1s de la cual se juega buena parte del derecho.<\/p>\n\n\n\n<p>Es deber de la Justicia procurar que los ciudadanos reivindiquen sus derechos cuando son vulnerados. El uso de tasas de inter\u00e9s reales negativas espanta cualquier reivindicaci\u00f3n de derechos, ya que al incordio de tramitar una causa judicial se suma la injusticia de conseguir devaluada la acreencia o el valor que se fue a buscar. Eso desalienta la reivindicaci\u00f3n judicial de los derechos.<\/p>\n\n\n\n<p><strong>6. Conclusiones<\/strong><\/p>\n\n\n\n<p>En el contexto actual la tasa de inter\u00e9s cumple la doble funci\u00f3n de servir como precio del cr\u00e9dito y a la vez sirve para recomponer el valor del capital. El an\u00e1lisis sobre la tasa de inter\u00e9s deber\u00eda pasar fundamentalmente por el \u00e9xito o el fracaso en el cumplimiento de esa doble funci\u00f3n que tiene asignada. La funci\u00f3n de recomposici\u00f3n de valor se mide de manera muy sencilla comparando el inter\u00e9s con la p\u00e9rdida de valor del signo monetario, que com\u00fanmente se mide con el \u00cdndice de Precios al Consumidor que publica el INDEC. La tasa de inter\u00e9s no debe beneficiar ni perjudicar injustificadamente a ninguna de las partes. Y sobre todo, no debe modificar la atribuci\u00f3n de derechos que se quiso consagrar en la sentencia. Cualquier alteraci\u00f3n injustificada del valor por la v\u00eda de la tasa de inter\u00e9s implica una afectaci\u00f3n del derecho constitucional de propiedad de una de las partes, y convierte en arbitrario el pronunciamiento. En el caso &#8216;Garc\u00eda&#8217; la CSJN conden\u00f3 el mecanismo de multiplicaci\u00f3n de tasas bancarias. Lo hizo partiendo de una interpretaci\u00f3n restrictiva del inciso C del art\u00edculo 768 del C.C.C.N., que no se condice con la flexibilidad que el propio legislador reconoci\u00f3 a la materia en los fundamentos del c\u00f3digo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>C\u00f3mo citar este art\u00edculo:<\/strong><\/td><\/tr><tr><td>Vald\u00e9s Tietjen, Benjam\u00edn (2023, agosto). Intereses. Tasas de inter\u00e9s para los da\u00f1os y perjuicios. Art\u00edculo 768 del CCCN. Implicancias del caso \u00abGarc\u00eda\u00bb de la CSJN. <em>Ius in fieri DDA.<\/em> www.iusinfieri.com.ar<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a href=\"#_ednref1\" id=\"_edn1\">[1]<\/a>CSJN, 7\/3\/23, &#8216;Garc\u00eda, Javier Omar c\/ UGOFE SA y otros s\/ da\u00f1os y perjuicios&#8217;, La Ley, cita online, AR\/JUR\/15607\/2023.-<\/p>\n\n\n\n<p><a href=\"#_ednref2\" id=\"_edn2\">[2]<\/a>A primera vista parece extra\u00f1o que uno le preste plata a un banco o que compre bonos soberanos que devuelvan menos plata de la que uno prest\u00f3. Sin embargo, en ciertos contextos excepcionales, como situaciones de guerra o de desastre natural, en que es riesgoso tener dinero en la mano, se han verificado tasas de inter\u00e9s negativas. Tambi\u00e9n se justifica el dep\u00f3sito a una tasa de inter\u00e9s negativa cuando se accede por esta v\u00eda a beneficios fiscales de alg\u00fan tipo.-<\/p>\n\n\n\n<p><a href=\"#_ednref3\" id=\"_edn3\">[3]<\/a>Ley de Convertibilidad del Austral N\u00b0 23.928 del 27\/3\/91.-<\/p>\n\n\n\n<p><a href=\"#_ednref4\" id=\"_edn4\">[4]<\/a>En el a\u00f1o 1992 el 25% anual, en 1993 el 11%, en 1994 el 5%, en 1995 el 4%, en 1996 solamente el 2% (fuente Universidad Torcuato Di Tella, departamento de Estudios Hist\u00f3ricos y Sociales, <a href=\"http:\/\/www.utdt.edu\/\">www.utdt.edu<\/a>).-<\/p>\n\n\n\n<p><a href=\"#_ednref5\" id=\"_edn5\">[5]<\/a>Caso &#8216;Massolo&#8217; de la Corte Suprema de Justicia de la Naci\u00f3n, Fallos: 333:447.-<\/p>\n\n\n\n<p><a href=\"#_ednref6\" id=\"_edn6\">[6]<\/a>Se supone que la prohibici\u00f3n de indexar permite aplacar la inflaci\u00f3n, evitando que los precios de la econom\u00eda se actualicen constantemente. Es evidente que se trata de una herramienta que ataca la consecuencia y no la causa del problema. Y tambi\u00e9n es evidente que la herramienta ha fracasado, porque llevamos m\u00e1s de 22 a\u00f1os de inflaci\u00f3n constante e ininterrumpida. Pero bueno, hay que reconocer que -en alguna medida y por escasa que sea- la prohibici\u00f3n de indexar opera como un ancla inflacionaria. La Corte de la Naci\u00f3n dijo expresamente en &#8216;Massolo&#8217; que la indexaci\u00f3n de precios &#8216;alimenta esa grave patolog\u00eda de la inflaci\u00f3n&#8217;. Por eso convalid\u00f3 la prohibici\u00f3n de indexar, para aplacar la inflaci\u00f3n.-<\/p>\n\n\n\n<p><a href=\"#_ednref7\" id=\"_edn7\">[7]<\/a>Ejemplo de esas alternativas se pueden ver en \u201cSenderos del nominalismo\u201d de Ariza, Ariel, La Ley 2010-F, 635, cita online: AR\/DOC\/6889\/2010.-<\/p>\n\n\n\n<p><a href=\"#_ednref8\" id=\"_edn8\">[8]<\/a>Habla claramente M\u00e9ndez Sierra: \u201c&#8230;. desde la vigencia de los arts. 7 y 10 de la ley 23.928 y, en consecuencia, de la prohibici\u00f3n absoluta de todo mecanismo de actualizaci\u00f3n, repotenciaci\u00f3n, reajuste o indexaci\u00f3n de las deudas dinerarias, los intereses han adquirido una particular trascendencia como mecanismo indirecto de recomposici\u00f3n de capital, aceptados impl\u00edcitamente por la ley 23.928. Subsistiendo al presente este r\u00e9gimen legal, pero ahora dentro de un proceso inflacionario que se ha incrementado en los \u00faltimos tiempos, esta v\u00eda indirecta es la \u00fanica defensa jur\u00eddicamente v\u00e1lida para paliar los efectos de aquella, esto es,&nbsp; la consiguiente p\u00e9rdida del poder adquisitivo de la moneda con el paso del tiempo.\u201d M\u00e9ndez Sierra, Eduardo, en &#8216;Obligaciones Dinerarias&#8217;, p\u00e1g. 236, editorial El Derecho, Buenos Aires, 2016.-<\/p>\n\n\n\n<p><a href=\"#_ednref9\" id=\"_edn9\">[9]<\/a>Vale la pena aclarar que el \u00cdndice de Precios al Consumidor es la f\u00f3rmula com\u00fanmente aceptada para medir la p\u00e9rdida del valor de la moneda, pero no es la \u00fanica, y a veces no es la m\u00e1s adecuada. Por ejemplo, si quien se vio privado de su dinero es un empresario de la construcci\u00f3n, puede que en su caso la gu\u00eda m\u00e1s fiel para conocer la p\u00e9rdida del valor de su dinero sea el \u00cdndice de la C\u00e1mara de la Construcci\u00f3n, que es el que mide el costo espec\u00edfico de la construcci\u00f3n. Se tratar\u00eda de un \u00edndice m\u00e1s apropiado en funci\u00f3n del sujeto afectado. Pero bueno, se tratar\u00eda de una disquisici\u00f3n a realizar en contadas ocasiones.-<\/p>\n\n\n\n<p><a href=\"#_ednref10\" id=\"_edn10\">[10]<\/a>Dice V\u00e1zquez Ferreyra que \u201cEl tema de las obligaciones de dar sumas de dinero es uno de los m\u00e1s \u00e1ridos del Derecho de las Obligaciones; y dentro de ese cap\u00edtulo, el de los intereses es uno de los que m\u00e1s ha ocupado la atenci\u00f3n de la doctrina y jurisprudencia; tal vez por los des\u00f3rdenes econ\u00f3micos que sufrimos los argentinos desde hace d\u00e9cadas.\u201d. V\u00e1zquez Ferreyra, Roberto, &#8216;Los intereses dinerarios en un trascendente fallo de la Corte Suprema&#8217;, La Ley, 28\/3\/23, cita online: AR\/DOC\/638\/2023.-<\/p>\n\n\n\n<p><a href=\"#_ednref11\" id=\"_edn11\">[11]<\/a>Un debate <em>in extenso<\/em> de este tema se dio en el reconocido precedente &#8216;Samudio&#8217;, de la C\u00e1mara Nacional Civil en pleno, del 20\/4\/09 (SJA 3\/6\/2009, 70052031), cuyos fundamentos conservan candente actualidad.-<\/p>\n\n\n\n<p><a href=\"#_ednref12\" id=\"_edn12\">[12]<\/a>En el frecuente escenario escenario en que se aplica una tasa pura desde la fecha de la mora hasta la fecha de la sentencia y a partir de all\u00ed se aplica una tasa bancaria, esa tasa bancaria debe entenderse aplicable desde la misma fecha en que se dicta la sentencia, y no desde que queda firme el pronunciamiento. Como veremos m\u00e1s adelante, lo que importa es el momento en que se expresa el valor en t\u00e9rminos nominales. Desde ese mismo momento se justifica la aplicaci\u00f3n de una tasa bancaria.-<\/p>\n\n\n\n<p><a href=\"#_ednref13\" id=\"_edn13\">[13]<\/a>Lo dice con toda claridad M\u00e9ndez Sierra: \u201c&#8230; cabe hacer una excepci\u00f3n a la aplicaci\u00f3n de tasas activas en los casos de deudas de valor en los cuales al momento del fallo se liquide en dinero el mismo fijado a valores actuales. Aqu\u00ed, los intereses deben liquidarse a raz\u00f3n del 6% al 8% anual hasta el momento del decisorio, esto es, a una tasa de inter\u00e9s puro; ya que las tasas activas -y aun las pasivas- incluyen entre sus componentes una prima por desvalorizaci\u00f3n de la moneda, factor este ausente en estas circunstancias. Por consiguiente, utilizarlas en este per\u00edodo implicar\u00eda conceder un enriquecimiento injustificado.\u201d M\u00e9ndez Sierra, Eduardo, en &#8216;Obligaciones Dinerarias&#8217;, p\u00e1g. 240, Ob. Cit.-<\/p>\n\n\n\n<p><a href=\"#_ednref14\" id=\"_edn14\">[14]<\/a>CSJN, 7\/3\/23, &#8216;Garc\u00eda, Javier Omar c\/ UGOFE SA y otros s\/ da\u00f1os y perjuicios&#8217;, La Ley, cita online, AR\/JUR\/15607\/2023.-<\/p>\n\n\n\n<p><a href=\"#_ednref15\" id=\"_edn15\">[15]<\/a>Suma perplejidad el hecho que pone de manifiesto Federico Ossola, de que no hay una reglamentaci\u00f3n especial del Banco Central que indique cu\u00e1l es la tasa de inter\u00e9s que se debe aplicar en este supuesto. Ossola, Federico A. en \u201cLos intereses moratorios en el fallo &#8216;Garc\u00eda&#8217; de la Corte Suprema. Una respuesta y varios interrogantes.\u201d, La Ley 28\/3\/23, cita online: AR\/DOC\/637\/2023. Esa remisi\u00f3n legal a las &#8216;tasas fijadas seg\u00fan las reglamentaciones del Banco Central&#8217; del art\u00edculo 768 inciso C es para nosotros por dem\u00e1s ambigua y desconcertante.-<\/p>\n\n\n\n<p><a href=\"#_ednref16\" id=\"_edn16\">[16]<\/a>Nos referimos aqu\u00ed al reconocido precedente &#8216;Colalillo&#8217; de la CSJN, Fallos: 238:550.-<\/p>\n\n\n\n<p><a href=\"#_ednref17\" id=\"_edn17\">[17]<\/a>De los Fundamentos del C\u00f3digo Civil y Comercial de la Naci\u00f3n, Libro tercero, punto 6, &#8216;Obligaciones de dar dinero&#8217;.-<\/p>\n\n\n\n<p><a href=\"#_ednref18\" id=\"_edn18\">[18]<\/a>Dijo sobre este tema M\u00e9ndez Sierra que \u201c&#8230; es obvio que existen situaciones en que resultar\u00edan inaplicables las tasas que publica el Banco Central. Tal el caso previsto en el art. 772 CC y C, donde, liquidada la deuda de valor -ej. el da\u00f1o- con referencia a su valor real al momento de la sentencia, al serlo en su valoraci\u00f3n pecuniaria actual, corresponder\u00eda hasta ese momento aplicar un inter\u00e9s puro -del 6 u 8%- y no las tasas, sean activas o pasivas, que surgen de las publicaciones de dicha entidad.\u201d M\u00e9ndez Sierra, Eduardo, en &#8216;Obligaciones Dinerarias&#8217;, p\u00e1g. 232, Ob. Cit.-<\/p>\n\n\n\n<p><a href=\"#_ednref19\" id=\"_edn19\">[19]<\/a>Coincidimos plenamente con Cossari cuando dice que \u201cen \u00e9pocas gravemente inflacionarias -como la que lamentablemente nos toca vivir en la actualidad- es importante que para que la indemnizaci\u00f3n por da\u00f1o moratorio sea verdaderamente &#8216;plena&#8217;, la tasa de inter\u00e9s aplicada debe ser suficiente para cubrir la depreciaci\u00f3n monetaria&#8230; De nada servir\u00eda otorgar una indemnizaci\u00f3n que se desvanezca con el tiempo por el retardo injustificado del deudor en el cumplimiento de la sentencia.\u201d Cossari, Maximiliano, \u201c\u00bfCu\u00e1l es la tasa de inter\u00e9s moratorio que corresponde aplicar en un caso de da\u00f1os y perjuicios?\u201d, La Ley, 13\/4\/23, cita online: AR\/DOC\/784\/2023.-&nbsp;<\/p>\n<div style=\"margin: 20px 0;\"><div class=\"qrcswholewtapper\" style=\"text-align:right;\"><div class=\"qrcprowrapper\"  id=\"qrcwraa2leds\"><div class=\"qrc_canvass\" id=\"qrc_cuttenpages_2\" style=\"display:inline-block\" data-text=\"https:\/\/iusinfieri.com.ar\/index.php\/2023\/08\/23\/intereses-tasas-de-interes-para-los-danos-y-perjuicios-articulo-768-del-cccn-implicancias-del-caso-garcia-de-la-csjn\/\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>SUMARIO: 1.Introducci\u00f3n. 2. Qu\u00e9 es el inter\u00e9s y para qu\u00e9 sirve. 3. El inter\u00e9s como mecanismo indirecto de recomposici\u00f3n de valor. 4. Tasas de inter\u00e9s y da\u00f1os y perjuicios. 5. La multiplicaci\u00f3n de tasas bancarias. <a class=\"mh-excerpt-more\" href=\"https:\/\/iusinfieri.com.ar\/index.php\/2023\/08\/23\/intereses-tasas-de-interes-para-los-danos-y-perjuicios-articulo-768-del-cccn-implicancias-del-caso-garcia-de-la-csjn\/\" title=\"Intereses. Tasas de inter\u00e9s para los da\u00f1os y perjuicios. Art\u00edculo 768 del CCCN. Implicancias del caso \u00abGarc\u00eda\u00bb de la CSJN\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":8,"featured_media":343,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[23,4,13],"tags":[87,85,86,64],"class_list":{"0":"post-455","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-art","8":"category-dpr","9":"category-responsabilidad_civil","10":"tag-danos-y-perjuicios","11":"tag-interes","12":"tag-intereses","13":"tag-jurisprudencia"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":2,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/455\/revisions"}],"predecessor-version":[{"id":458,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/455\/revisions\/458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/media\/343"}],"wp:attachment":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}