{"id":87,"date":"2022-02-24T06:14:00","date_gmt":"2022-02-24T09:14:00","guid":{"rendered":"http:\/\/iusinfieri.com.ar\/?p=87"},"modified":"2022-06-27T23:21:03","modified_gmt":"2022-06-28T02:21:03","slug":"prueba-del-dano-moral-en-acciones-de-consumo","status":"publish","type":"post","link":"https:\/\/iusinfieri.com.ar\/index.php\/2022\/02\/24\/prueba-del-dano-moral-en-acciones-de-consumo\/","title":{"rendered":"Prueba del da\u00f1o moral en acciones de consumo"},"content":{"rendered":"\n<p><strong>SUMARIO: I. Proemio. Descripci\u00f3n metodol\u00f3gica. II. Generalidades del rubro indemnizatorio de marras. III. Prueba del da\u00f1o moral. IV. Los deberes del proveedor con relaci\u00f3n a la prueba.<\/strong><\/p>\n\n\n\n<p><strong>I. Proemio. Descripci\u00f3n metodol\u00f3gica<\/strong><\/p>\n\n\n\n<p>En este op\u00fasculo procuraremos plasmar algunas precisiones sobre la prueba del da\u00f1o moral en el marco de un proceso de consumo. En dicho tren, segmentaremos en el estudio en tres partes, a saber: primeramente una somera descripci\u00f3n sobre nociones generales del da\u00f1o moral o, en la designaci\u00f3n del CCCN en el art\u00edculo 1741, la indemnizaci\u00f3n de las consecuencias no patrimoniales; luego, desarrollaremos las especificidades de la prueba de dicho rubro intentando cohonestar el requisito inexcusable de la prueba del da\u00f1o con la dificultad pr\u00e1ctica de aportaci\u00f3n de prueba directa que atestig\u00fce acabadamente el sufrimiento o zozobra personal y, finalmente, abordaremos un aspecto espec\u00edfico de la prem\u00e1tica consumeril como es el art\u00edculo 53 de la LDC el cual reconoce un trascendencia central sobre el r\u00e9gimen de la prueba en las acciones de consumo.<\/p>\n\n\n\n<p><strong>II. Generalidades del rubro indemnizatorio de marras<\/strong><\/p>\n\n\n\n<p>Debe destacarse que el CCCN mantiene un doble r\u00e9gimen sobre la naturaleza del da\u00f1o: el mismo patrimonial o no patrimonial. Dentro del primero se ubican la p\u00e9rdida o disminuci\u00f3n del patrimonio de la v\u00edctima, el lucro cesante y la p\u00e9rdida de chance. Dentro del segundo se inscriben los da\u00f1os a la integridad personal, a la salud psicof\u00edsica y a sus afecciones espirituales leg\u00edtimas (da\u00f1o moral en sentido tradicional)<a href=\"#_edn1\"><sup>[1]<\/sup><\/a>. <\/p>\n\n\n\n<p>Es decir, en el caso del da\u00f1o patrimonial se disminuye el patrimonio actual o futuro de una persona afect\u00e1ndose un inter\u00e9s tambi\u00e9n patrimonial mientras que el da\u00f1o extrapatrimonial lesiona un inter\u00e9s no patrimonial m\u00e1s all\u00e1 que se pueda cuantificar y traducirse la lesi\u00f3n en t\u00e9rminos monetarios<a href=\"#_edn2\"><sup>[2]<\/sup><\/a>. Se trata, en suma, de dos categor\u00edas de da\u00f1os fundamentales las que adem\u00e1s comprenden diferentes menoscabos seg\u00fan la \u00edndole de las consecuencias que se produzcan (patrimoniales o no)<a href=\"#_edn3\"><sup>[3]<\/sup><\/a>.<\/p>\n\n\n\n<p>La explicaci\u00f3n precedente se construye de la lectura arm\u00f3nica de varios art\u00edculos del CCCN ya que dicho cuerpo normativo define al da\u00f1o en el art\u00edculo 1737, lo clasifica impl\u00edcitamente en las dos especies ya apuntadas en el 1738, cuando precisa el contenido de la indemnizaci\u00f3n y luego pasa a asignarle un r\u00e9gimen espec\u00edfico a las consecuencias no patrimoniales en el art\u00edculo 1741 aunque ilustrando con \u00e9nfasis su contenido en el precitado art\u00edculo 1738 <em>in fine<\/em>: \u201c<em>\u2026incluye especialmente las consecuencias de la violaci\u00f3n de los derechos personal\u00edsimos de la v\u00edctima, de su integridad personal, su salud psicof\u00edsica, sus afecciones espirituales leg\u00edtimas y las que resultan de la interferencia en su proyecto de vida<\/em>\u201d.<\/p>\n\n\n\n<p>Entendiendo, en suma, que en el esquema del CCCN el da\u00f1o resarcible reconoce dos especies (patrimonial y extrapatrimonial) podemos definir esta \u00faltima<a href=\"#_edn4\"><sup>[4]<\/sup><\/a> como una modificaci\u00f3n disvaliosa del esp\u00edritu de una persona, tambi\u00e9n producto de la lesi\u00f3n a un inter\u00e9s extrapatrimonial, que reposa sobre un derecho de naturaleza patrimonial o extrapatrimonial y que se traduce en un modo de estar de la persona distinto producto de ese hecho lesivo y an\u00edmicamente perjudicial<a href=\"#_edn5\"><sup>[5]<\/sup><\/a>. Con similares palabras, tambi\u00e9n se lo ha conceptualizado como una modificaci\u00f3n disvaliosa del esp\u00edritu en el desenvolvimiento de la capacidad de entender, querer o sentir del ser humano<a href=\"#_edn6\"><sup>[6]<\/sup><\/a>.<\/p>\n\n\n\n<p>En cuanto a los requisitos de procedencia del da\u00f1o extrapatrimonial resarcible, aunque el estudio de ellos, se\u00f1ala Pizarro<a href=\"#_edn7\"><sup>[7]<\/sup><\/a>, suele circunscribirse de manera principal al da\u00f1o patrimonial, lo cierto es que esos mismos requisitos son los necesarios para que se configure el da\u00f1o resarcible no patrimonial. Recordemos, ellos han sido prefijados en el art\u00edculo 1739 del CCCN al decir que debe existir un perjuicio directo o indirecto, actual o futuro, cierto y subsistente.<\/p>\n\n\n\n<p>Siempre ha sido campo fecundo para la controversia determinar en qu\u00e9 supuestos, de corresponder, resulta admisible como rubro indemnizatorio el da\u00f1o moral, cuando el hecho generador de los da\u00f1os y perjuicios reclamados radica en alguna vicisitud del devenir en la vigencia de un contrato como bien podr\u00eda ocurrir en el esquema de tutela al consumidor. Como apreciar\u00e1 el lector, esta problem\u00e1tica participa de una mayor, la cual radica en delimitar los contornos de una figura siempre compleja como es el da\u00f1o moral cuyos requisitos de procedencia y prueba se hallan, las m\u00e1s de las veces, cuestionados<a href=\"#_edn8\"><sup>[8]<\/sup><\/a>.<\/p>\n\n\n\n<p>Finalmente, en orden al fin asequible mediante el reconocimiento del da\u00f1o moral, es&nbsp;&nbsp; pac\u00edfico que el mismo tiene como norte, no una finalidad reparatoria o de equivalencia entre el perjuicio sufrido y lo recibido a cambio, sino \u201csatisfactoria\u201d (o satisfactiva), de \u201cconsuelo\u201d<a href=\"#_edn9\"><sup>[9]<\/sup><\/a>, siendo esta \u00faltima funci\u00f3n reafirmada expresamente respecto del Estado por la Corte Suprema de Justicia de la Naci\u00f3n en el conocido precedente \u201c<em>Baeza<\/em>\u201d<a href=\"#_edn10\"><sup>[10]<\/sup><\/a>. Es que, la especialidad ontol\u00f3gica del rubro impide que la indemnizaci\u00f3n directa (en especie o en dinero que vuelva las cosas al estado anterior) sea factible, pues la indemnizaci\u00f3n no podr\u00eda resarcir de modo completo el perjuicio espiritual sufrido por el actor y por ello es que la asignaci\u00f3n del deber reparatorio procura medios de satisfacci\u00f3n alternativos a trav\u00e9s del pago de la indemnizaci\u00f3n que puedan intentar equilibrar los bienes extrapatrimoniales de la v\u00edctima remitiendo el dolor, angustia o zozobra que le ha irrogado el hecho da\u00f1oso.<\/p>\n\n\n\n<p><strong>III. Prueba del da\u00f1o moral<\/strong><\/p>\n\n\n\n<p>Continuando, es claro que el da\u00f1o debe ser cierto y no puramente eventual o hipot\u00e9tico; esto significa que debe haber certidumbre en cuanto a la existencia misma, presente o futura, aunque pueda no ser todav\u00eda determinable su monto<a href=\"#_edn11\"><sup>[11]<\/sup><\/a> lo cual se enlaza y acerca con la prueba del da\u00f1o moral el cual, como todo da\u00f1o, debe ser acreditado por quien lo alega (art\u00edculo 1744 del CCCN), pero tal entendimiento se relaja, seg\u00fan la doctrina, dada la posibilidad de que a partir de la acreditaci\u00f3n del evento lesivo y del car\u00e1cter de legitimado activo del actor, puede operar la prueba de indicios o la prueba presuncional, e inferirse la existencia del da\u00f1o moral. La prueba&nbsp;indirecta&nbsp;del da\u00f1o moral encuentra en los indicios y en las presunciones&nbsp;<em>hominis<\/em>, su modo natural de realizaci\u00f3n, toda vez que, se ha destacado, los indicios o presunciones constituyen un medio de prueba y, por lo tanto, cuando se acude a ellos para demostrar, por v\u00edas indirectas, la existencia del perjuicio,&nbsp;se est\u00e1 realizando una actividad t\u00edpicamente probatoria<a href=\"#_edn12\"><sup>[12]<\/sup><\/a>.<\/p>\n\n\n\n<p>Esta conclusi\u00f3n es arm\u00f3nica con el precitado art\u00edculo 1744 del CCCN ya que acudir a presunciones <em>hominis<\/em> y a la regla <em>res ipsa loquitur<\/em><a href=\"#_edn13\"><sup>[13]<\/sup><\/a> es cumplir justamente con su letra toda vez que la segunda parte de la norma releva de la carga de la prueba al damnificado cuando la ley impute el da\u00f1o, lo presuma, o que el mismo surja notorio de los propios hechos. Como apunta Ossola<a href=\"#_edn14\"><sup>[14]<\/sup><\/a>, por las reglas de la experiencia es m\u00e1s o menos sencillo concluir que ciertos padecimientos y afecciones naturalmente se derivan de determinados hechos acreditados.<\/p>\n\n\n\n<p>En esta l\u00ednea, se ha dicho que para probar el da\u00f1o moral en su existencia e identidad no es necesario aportar prueba directa pues ello resulta absolutamente imposible, dada la \u00edndole del mismo que reside en lo m\u00e1s m\u00ednimo de la personalidad, aunque se manifieste a veces por signos exteriores que pueden no ser su aut\u00e9ntica expresi\u00f3n<a href=\"#_edn15\"><sup>[15]<\/sup><\/a>. Entonces, mucho m\u00e1s simple ser\u00e1 colegir el agravio moral en aquellos supuestos en los cuales la prueba producida sobre la ocurrencia de los hechos sea clara puesto que, ante la innegable dificultad de acreditar un padecimiento personal e interno, las presunciones judiciales construidas en base a los hechos ocurridos en una herramienta central y definitoria.<\/p>\n\n\n\n<p>Claro es que el da\u00f1o moral no es posible producir una prueba directa sobre el nocimiento padecido porque la \u00edndole espiritual y subjetiva del perjuicio no es susceptible de esa forma de acreditaci\u00f3n, entonces, nuevamente, a partir de la acreditaci\u00f3n del evento lesivo y del car\u00e1cter de legitimado activo del actor puede operar la prueba por indicios o presuncional e inferirse la existencia del da\u00f1o y, correlativamente, el demandado podr\u00e1 acreditar extremos que lleven indiciaria o presuncionalmente a inferir la existencia de una da\u00f1o menor al que ordinariamente deber\u00eda producirse o, lisa y llanamente, su inexistencia<a href=\"#_edn16\"><sup>[16]<\/sup><\/a>.<\/p>\n\n\n\n<p>En este sentido, si bien la carga de la prueba del da\u00f1o moral seguir\u00e1 pesando sobre los hombros de la v\u00edctima, la misma deber\u00e1 ponderarse con una mirada especial, pudiendo, en determinados supuestos, llegar a considerarse que el da\u00f1o moral surge <em>in re ipsa<\/em> de las circunstancias del caso<a href=\"#_edn17\"><sup>[17]<\/sup><\/a> dado que la esencia del da\u00f1o moral se demuestra a trav\u00e9s de la estimaci\u00f3n objetiva que har\u00e1 el juez de las presuntas modificaciones o alteraciones espirituales que afecten el equilibrio emocional de la v\u00edctima y, por ello, para probar este aspecto habr\u00e1n de aportarse elementos probatorios que lleven a la conciencia del juez el convencimiento de la existencia de circunstancias objetivamente reveladoras de la presencia del perjuicio y su entidad<a href=\"#_edn18\"><sup>[18]<\/sup><\/a>.<\/p>\n\n\n\n<p>De este modo, se revitaliza la importancia de una correcta delimitaci\u00f3n y acreditaci\u00f3n de los hechos de la causa toda vez que su prueba pasar\u00e1 a adquirir, seg\u00fan el criterio que sustentamos, una trascendencia nada desde\u00f1able a la hora de poder discernir el juzgador no s\u00f3lo la existencia del nocimiento extrapatrimonial sino, adem\u00e1s, la magnitud e impacto del mismo. Por ello, se impone una argumentaci\u00f3n precisa en orden a coligar o desvincular -seg\u00fan la decisi\u00f3n a adoptarse- la ocurrencia del hecho con las consecuencias que de \u00e9l dimanan.<\/p>\n\n\n\n<p>Tambi\u00e9n puede entrar a tallar aqu\u00ed la construcci\u00f3n de los llamados \u201cda\u00f1os morales m\u00ednimos\u201d vincul\u00e1ndolos al tiempo que le ha insumido a la v\u00edctima el reclamo y, en caso de existir, la curaci\u00f3n de sus lesiones -tr\u00e1mites judiciales y administrativos, esperas prolongadas, visitas a profesionales del arte de curar, etc.-, tiempo en el cual se ha visto privado de desarrollar sus tareas habituales<a href=\"#_edn19\"><sup>[19]<\/sup><\/a>. Compartiendo esta postura, ense\u00f1a Barocelli que no solo deben ponderarse los impedimentos y molestias que le implicaron el incumplimiento, sino tambi\u00e9n el valor tiempo que ha perdido, tanto en relaci\u00f3n a la realizaci\u00f3n de diversos tr\u00e1mites vinculados con el mismo (cuestiones administrativas y\/o judiciales que precedieron el inicio de la acci\u00f3n)<a href=\"#_edn20\"><sup>[20]<\/sup><\/a>.<\/p>\n\n\n\n<p><strong>IV. Los deberes del proveedor con relaci\u00f3n a la prueba<\/strong><\/p>\n\n\n\n<p>Definida que fuera la vinculaci\u00f3n funcional entre las particularidades de ocurrencia del hecho y su prueba con la inferencia del da\u00f1o moral como rubro indemnizatorio, se impone a nuestro criterio incorporar al an\u00e1lisis una norma de la LDC de gran relevancia a los efectos probatorios en acciones de consumo como es el art\u00edculo 53, incorporado a la normativa de defensa del consumidor en el a\u00f1o 2008 mediante la reforma a la ley 24.240 operada mediante la ley 26.361.<\/p>\n\n\n\n<p>El art\u00edculo 53 de la LDC obliga al proveedor a aportar al proceso todas las pruebas que se encuentren en su poder, conforme a las caracter\u00edsticas del bien o servicio, imponi\u00e9ndole adem\u00e1s una obligaci\u00f3n adicional de car\u00e1cter gen\u00e9rico: prestar la colaboraci\u00f3n necesaria para el esclarecimiento de la cuesti\u00f3n debatida en el juicio. La soluci\u00f3n responde a que la superioridad t\u00e9cnica -muchas veces acompa\u00f1ada por preeminencia econ\u00f3mica- que detenta el proveedor, la cual le permite asimismo contar con cierta superioridad jur\u00eddica, redunda las m\u00e1s de las veces en un f\u00e1cil acceso a extremos relevantes para liberarse de responsabilidad propia y\/o para fundar la ajena.<\/p>\n\n\n\n<p>De todos modos, la figura ha sido materia de debate sobre todo en orden a definir si importa o no una consagraci\u00f3n normativa expresa de la teor\u00eda de las cargas probatorias din\u00e1micas. Tres respuestas se esbozaron sobre el t\u00f3pico: por un lado, autores coligen que el art\u00edculo 53 de la LDC no incorpora las cargas probatorias din\u00e1micas a favor del consumidor, tampoco prev\u00e9 un \u201cdeber de colaboraci\u00f3n\u201d porque no sanciona su incumplimiento<a href=\"#_edn21\"><sup>[21]<\/sup><\/a>; luego, se ha puesto el foco en el \u201cdeber de colaboraci\u00f3n\u201d del proveedor como par\u00e1metro de conducta cuya inobservancia aparejar\u00eda un indicio corroborante de pruebas y, finalmente, otros autores pregonan la adscripci\u00f3n del legislador a la teor\u00eda de las cargas probatorias din\u00e1micas en el \u00e1mbito consumeril.<\/p>\n\n\n\n<p>Desbrozando la segunda tesis apuntada, se ha manifestado que la norma s\u00f3lo que pone en cabeza del proveedor el deber de aportar al proceso los elementos de prueba que se encuentren en su poder, pero no determina que recae sobre \u00e9l la carga de producir la prueba correspondiente. No se tratar\u00eda por tanto de una inversi\u00f3n de la carga probatoria sino m\u00e1s bien de un deber de colaboraci\u00f3n de car\u00e1cter agravado establecido en cabeza del proveedor<a href=\"#_edn22\"><sup>[22]<\/sup><\/a> que operar\u00eda como un indicio que habr\u00e1 de valorarse dentro del incumplimiento del deber de colaboraci\u00f3n junto con las restantes constancias correspondientes.<\/p>\n\n\n\n<p>El M\u00e1ximo Tribunal santafesino, en esta l\u00ednea, arguy\u00f3&nbsp; que si bien el art\u00edculo 53 LDC no establece una inversi\u00f3n de la carga probatoria, s\u00ed prefija en cabeza del proveedor el deber de prestar la colaboraci\u00f3n procesal necesaria para el esclarecimiento de la cuesti\u00f3n debatida en el juicio y, puntualmente, de aportar al proceso todos los elementos de prueba que obren en su poder conforme a las caracter\u00edsticas del bien o servicio, cuyo incumplimiento podr\u00eda acarrear un indicio en su contra seg\u00fan las circunstancias<a href=\"#_edn23\"><sup>[23]<\/sup><\/a>.<\/p>\n\n\n\n<p>Por el contrario, otros autores derechamente coligen una consagraci\u00f3n legislativa de las cargas probatorias din\u00e1micas<a href=\"#_edn24\"><sup>[24]<\/sup><\/a> con basamento, por un lado, en el art\u00edculo 3 de la LDC que manda a interpretar la norma en el sentido que m\u00e1s favorezca al consumidor y, por el otro, que el esp\u00edritu hermen\u00e9utico de la LDC se endereza a restablecer el desequilibrio dado por la vulnerabilidad del consumidor y, as\u00ed, la teor\u00eda de las cargas probatorias din\u00e1micas importa una herramienta m\u00e1s para restablecer dicho desequilibrio<a href=\"#_edn25\"><sup>[25]<\/sup><\/a>. Incluso Shina no duda en afirmar contundentemente que el nombre de \u201cdeber de colaboraci\u00f3n\u201d es un eufemismo para definir la verdadera obligaci\u00f3n procesal (carga) que se pone en cabeza del proveedor demandado<a href=\"#_edn26\"><sup>[26]<\/sup><\/a>.<\/p>\n\n\n\n<p>Por fuera del debate apuntado, se\u00f1ala Chamatropulos con un criterio pr\u00e1ctico, que en los hechos aplicar esta soluci\u00f3n normativa conlleva a resultados similares a los de la teor\u00eda de las cargas probatorias din\u00e1micas, a partir de una correcta interpretaci\u00f3n del deber de colaboraci\u00f3n procesal puesto en cabeza del proveedor y de las circunstancias f\u00e1cticas que rodean a las relaciones de consumo en particular<a href=\"#_edn27\"><sup>[27]<\/sup><\/a>. Por ejemplo, en materia de lesiones sufridas en un gimnasio se consider\u00f3 que un an\u00e1lisis integral de los antecedentes determina que quien explota el establecimiento, bien pudo acercar al proceso prueba relativa a las caracter\u00edsticas de la m\u00e1quina \u201cmultifuerza\u201d, a fin de constatar su correcto funcionamiento<a href=\"#_edn28\"><sup>[28]<\/sup><\/a>.<\/p>\n\n\n\n<p>Es que ambas instituciones podr\u00edan culminar produciendo un resultado muy similar en la pr\u00e1ctica puesto que teniendo en cuenta la din\u00e1mica propia de las relaciones de consumo, ser\u00e1 quien tiene en su poder gran parte de la prueba que puede ser definitoria en estos litigios. Comoquiera que sea, y si bien se trata de institutos jur\u00eddicos claramente diferenciados, tanto sea a trav\u00e9s de la aplicaci\u00f3n de la teor\u00eda de la carga probatoria din\u00e1mica o de la inferencia de un deber de colaboraci\u00f3n agravado en cabeza del proveedor, lo relevante es la factibilidad de verificar en el pleito elementos de convicci\u00f3n suficientes para juzgar la procedencia de las respectivas pretensiones seg\u00fan las reglas de la sana cr\u00edtica.<\/p>\n\n\n\n<p>As\u00ed lo ha definido la Suprema Corte bonaerense: \u201c<em>es notorio que la empresa demandada, atento a su profesionalidad es quien est\u00e1 en mejores condiciones para acreditar ciertos extremos. Deb\u00eda al menos poner a disposici\u00f3n el material para posibilitar la actividad probatoria<\/em>\u201d<a href=\"#_edn29\"><sup>[29]<\/sup><\/a>, casos que Lorenzetti engloba como supuestos en los que la empresa elimina prueba en perjuicio del consumidor, no colabora en esclarecer el asunto o destruye documentaci\u00f3n relevante<a href=\"#_edn30\"><sup>[30]<\/sup><\/a>.<\/p>\n\n\n\n<p>Lo dicho no implica liberar al consumidor de acreditar los extremos en que basa su pretensi\u00f3n<a href=\"#_edn31\"><sup>[31]<\/sup><\/a> dado que m\u00ednimamente deber\u00e1, por ejemplo, acreditar la relaci\u00f3n de consumo, los presupuestos de la configuraci\u00f3n del da\u00f1o, su cuant\u00eda, entre otras. En este sentido se ha se\u00f1alado, con buen criterio, que la modificaci\u00f3n hecha a la LDC asume las dificultades probatorias con que puede enfrentar el consumidor como contratante no profesional, pero ello no puede llevarnos a entender que el consumidor quede relevado de introducir medios de comprobaci\u00f3n id\u00f3neos para justificar la posici\u00f3n, raz\u00f3n por la cual al menos debe exig\u00edrsele que identifique eventuales carencias de su adversario en la adjunci\u00f3n de esos elementos, de modo de permitir el control judicial sobre este aspecto<a href=\"#_edn32\"><sup>[32]<\/sup><\/a>.<\/p>\n\n\n\n<p>Tambi\u00e9n debe destacarse que, efectuando una interpretaci\u00f3n sistem\u00e1tica de la normativa, el art\u00edculo 53 aludido deber\u00e1 integrarse con el art\u00edculo 37 inciso c) de la LDC, el cual dispone tener por no escritas -por abusivas- las cl\u00e1usulas que contengan cualquier precepto que imponga la inversi\u00f3n de la carga de la prueba en perjuicio del consumidor.<\/p>\n\n\n\n<p>Si bien la dilucidaci\u00f3n del debate excede notoriamente estas l\u00edneas, resultaba pertinente por lo pronto presentarlo dentro de la amplia tem\u00e1tica de la prueba en las relaciones de consumo puesto que, en el caso concreto, sin dudas que reconoce una trascendencia de fuste para la acreditaci\u00f3n de los hechos que suscitan la lid judicial y que, como apunt\u00e1ramos, tienen la virtualidad de incidir en la viabilidad de la indemnizaci\u00f3n de las consecuencias no patrimoniales del hecho il\u00edcito.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><a href=\"#_ednref1\">[1]<\/a> BERGER, Sabrina M., <em>La clasificaci\u00f3n de los da\u00f1os en el nuevo C\u00f3digo Civil y Comercial de la Naci\u00f3n<\/em>, RCyS 2015-X, 34, Cita online: AR\/DOC\/2467\/2015.<\/p>\n\n\n\n<p><a href=\"#_ednref2\">[2]<\/a> MOLINA SALNDOVAL, Carlos A., <em>Derecho de da\u00f1os<\/em>, Hammurabi, Buenos Aires, 2020, p. 335.<\/p>\n\n\n\n<p><a href=\"#_ednref3\">[3]<\/a> COMPAGNUCCI DE CASO, Rub\u00e9n H., <em>Derecho de las obligaciones<\/em>, La Ley, Buenos Aires, 2018, p. 764.<\/p>\n\n\n\n<p><a href=\"#_ednref4\">[4]<\/a> Seguimos aqu\u00ed a Brebbia, quien sostuvo que los da\u00f1os morales, los derechos personal\u00edsimos y los bienes personales protegidos por \u00e9stos, forman una trilog\u00eda indisoluble que constituye el n\u00facleo de la teor\u00eda jur\u00eddica de los agravios extrapatrimoniales, ver, BREBBIA, Roberto H., <em>Instituciones de Derecho Civil<\/em>, Juris, Rosairo, 1997, t. II, p. 403.<\/p>\n\n\n\n<p><a href=\"#_ednref5\">[5]<\/a> OSSOLA, Federico A., <em>Responsabilidad Civil<\/em>, Abeledo-Perrot, Buenos Aires, 2017, p. 140.<\/p>\n\n\n\n<p><a href=\"#_ednref6\">[6]<\/a> Dicho concepto fue utilizado por la CNCiv., sala M, en autos \u201c<em>Lisarrague, Mar\u00eda I. c\/ Autotransporte Adesmar S.A. y otros<\/em>\u201d, publicado en La Ley 03\/09\/2007 citado por GHERSI, Carlos A., <em>La importancia de los derechos del consumidor. El da\u00f1o moral per se y el da\u00f1o punitivo<\/em>, La Ley C\u00f3rdoba 2012 (noviembre), 1049, Cita online: AR\/DOC\/5571\/2012.<\/p>\n\n\n\n<p><a href=\"#_ednref7\">[7]<\/a> PIZARRO, Ram\u00f3n D., <em>Da\u00f1o moral<\/em>, Hammurabi, Buenos Aires, 1996, p. 124.<\/p>\n\n\n\n<p><a href=\"#_ednref8\">[8]<\/a> V. gr. la legitimaci\u00f3n para reclamarlo a t\u00edtulo personal y la exclusi\u00f3n en el art\u00edculo 1741 de damnificados que claramente deber\u00edan hallarse habilitados a tales efectos como podr\u00eda ser un hermano no conviviente; la exigencia de prueba del da\u00f1o del art\u00edculo 1744 y c\u00f3mo acoplar dicha exigencia al car\u00e1cter personal del padecimiento; si las personas jur\u00eddicas pueden sufrir este perjuicio o no; su naturaleza sancionatoria, represiva, indemnizatoria o sustitutiva; la cuantificaci\u00f3n del mismo en base a la naturaleza; qu\u00e9 limitaciones, si es que reconoce alguna, cabe asignarle al \u201cdeber\u201d del juez de otorgarlo, entre otros aspectos.<\/p>\n\n\n\n<p><a href=\"#_ednref9\">[9]<\/a> UBIR\u00cdA, Fernando A., <em>Derecho de Da\u00f1os en el C\u00f3digo Civil y Comercial de la Naci\u00f3n<\/em>, Abeledo-Perrot, Buenos Aires, 2015, p. 321.<\/p>\n\n\n\n<p><a href=\"#_ednref10\">[10]<\/a> C.S.J.N., \u201c<em>Baeza, Silva Ofelia c\/ Provincia de Buenos Aires y otros s\/ da\u00f1os y perjuicios<\/em>\u201d, Fallos 334:376 (2011).<\/p>\n\n\n\n<p><a href=\"#_ednref11\">[11]<\/a> CAZEAUX, Pedro N. \u2013 TRIGO REPRESAS, F\u00e9lix A., <em>Derecho de las obligaciones<\/em>, Librer\u00eda Editora Platense S.R.L., Buenos Aires, 1987, t. I, p. 407.<\/p>\n\n\n\n<p><a href=\"#_ednref12\">[12]<\/a> MEZA, Jorge A. \u2013 BORAGINA, Juan C., <em>Carga de la prueba del da\u00f1o moral<\/em>, enDJ&nbsp;21\/11\/2012, 11, Cita Online: AR\/DOC\/5339\/2012.<\/p>\n\n\n\n<p><a href=\"#_ednref13\">[13]<\/a> Desde antiguo, autores italianos como Minozzi conclu\u00edan tajantemente que la prueba de los da\u00f1os morales existe <em>in re ipsa<\/em>. Ver, MINOZZI, Alfredo, <em>Studio sul danno non patrimoniale (danno morale)<\/em>, 3\u00aa edici\u00f3n, Societ\u00e0 Editrice Libraria, Milano, 1917, p. 59.<\/p>\n\n\n\n<p><a href=\"#_ednref14\">[14]<\/a> OSSOLA, Federico A., <em>Responsabilidad Civil<\/em>, <em>ob. cit.<\/em>, p. 159; MOLINA SANDOVAL, Carlos A., <em>Derecho de da\u00f1os<\/em>, <em>ob. cit<\/em>., p. 350; COMPAGNUCCI DE CASO, Rub\u00e9n H., <em>Derecho de las obligaciones<\/em>, <em>ob. cit<\/em>., p. 785.<\/p>\n\n\n\n<p><a href=\"#_ednref15\">[15]<\/a> BUSTAMANTE ALSINA, Jorge, <em>Teor\u00eda general de la responsabilidad civil<\/em>, 9\u00aa edici\u00f3n, Abeledo-Perrot, Buenos Aires, 1997, p. 247.&nbsp;<\/p>\n\n\n\n<p><a href=\"#_ednref16\">[16]<\/a> PIZARRO, Ram\u00f3n D. \u2013 VALLESPINOS, Carlos G., <em>Tratado de responsabilidad civil<\/em>, Rubinzal-Culzoni editores, Santa Fe, 2017, t. I, p. 219.<\/p>\n\n\n\n<p><a href=\"#_ednref17\">[17]<\/a> QUAGLIA, Marcelo C., <em>Aspectos jur\u00eddicos de las salideras bancarias<\/em>, La Ley Patagonia 2014 (abril), 135, Cita online: AR\/DOC\/1041\/2014.<\/p>\n\n\n\n<p><a href=\"#_ednref18\">[18]<\/a> Ver, BUSTAMANTE ALSINA, Jorge, <em>Equitativa valuaci\u00f3n del da\u00f1o no mensurable<\/em>, La Ley&nbsp;1990-A,&nbsp;654, Cita Online: AR\/DOC\/3850\/2001.&nbsp;<\/p>\n\n\n\n<p><a href=\"#_ednref19\">[19]<\/a> ZAVALA DE GONZALEZ, Matilde, <em>Los da\u00f1os morales m\u00ednimos<\/em>, La Ley 2004-E, 1311.<\/p>\n\n\n\n<p><a href=\"#_ednref20\">[20]<\/a>BAROCELLI, Sebasti\u00e1n, <em>El valor tiempo como menoscabo a ser reparado al consumidor, su cuantificaci\u00f3n<\/em>, publicado en Revista Jur\u00eddica de Da\u00f1os, el 31\/07\/2013, cita IJ-LXVIII-871.<\/p>\n\n\n\n<p><a href=\"#_ednref21\">[21]<\/a> FRISICALE, Mar\u00eda L., <em>La dificultad de la prueba en la responsabilidad por productos defectuosos. Reflexiones sobre el art\u00edculo 53 de la ley 24.240<\/em>, RCyS&nbsp;2020-VII,&nbsp;76, Cita Online: AR\/DOC\/250\/2020.&nbsp;<\/p>\n\n\n\n<p><a href=\"#_ednref22\">[22]<\/a> S\u00c1ENZ, Luis R. J. &#8211; SILVA, Rodrigo, en PICASSO, Sebasti\u00e1n &#8211; V\u00c1ZQUEZ FERREYRA, Roberto A. (directores), <em>Ley de Defensa del Consumidor comentada y anotada<\/em>, La Ley, Buenos Aires, 2009, t. I, p. 670; GIANNINI, Leandro J., <em>Principio de colaboraci\u00f3n y carga din\u00e1mica de la prueba (una distinci\u00f3n necesaria)<\/em>, La Ley 2010-F, 1136, Cita Online: AR\/DOC\/3487\/2016.<\/p>\n\n\n\n<p><a href=\"#_ednref23\">[23]<\/a> CSJSF, 27\/02\/2020, \u201c<em>Pasetto, Mar\u00eda In\u00e9s c\/ Alto Rosario Shopping \u2013 da\u00f1os y perjuicios<\/em>\u201d, A. y S., t. 295, pp. 420\/286; <em>\u00eddem<\/em>, 04\/04\/2017, \u201c<em>Belfer, Jaime y otros c\/ Electr\u00f3nica Megatone<\/em>\u201d, A. y S., t 274, pp. 280\/286.<\/p>\n\n\n\n<p><a href=\"#_ednref24\">[24]<\/a> PAG\u00c9S LLOVERAS, Roberto M., <em>Deber de seguridad, carga probatoria y sana cr\u00edtica en las relaciones de consumo<\/em>, La Ley 2013-D, 189, Cita Online: AR\/DOC\/1982\/2013; VINTI, \u00c1ngela M., <em>La carga din\u00e1mica de la prueba en la Ley de Defensa del Consumidor. Las consecuencias de la frustraci\u00f3n de la prueba<\/em>, La Ley Buenos Aires 2016 (febrero), 17, Cita Online: AR\/DOC\/363\/2016.<\/p>\n\n\n\n<p><a href=\"#_ednref25\">[25]<\/a> JUNYENT BAS, Francisco \u2013 GARZINO, Mar\u00eda C. \u2013 RODR\u00cdGUEZ JUNYENT, Santiago, <em>Cuestiones claves de derecho consumidor a la luz del C\u00f3digo Civil y Comercial<\/em>, Advocatus, C\u00f3rdoba, 2017, pp. 251-252 citando en su apoyo a Mart\u00ednez Medrano, Mosset Iturraspe, Wajntraub, Weingarten y Ghersi.<\/p>\n\n\n\n<p><a href=\"#_ednref26\">[26]<\/a> SHINA, Fernando A., <em>Sistema legal para la defensa del consumidor<\/em>, Astrea, Buenos Aires, 2016, p. 273.<\/p>\n\n\n\n<p><a href=\"#_ednref27\">[27]<\/a> CHAMATROPULOS, Demetrio A., <em>Estatuto del Consumidor Comentado,<\/em> La Ley, Buenos Aires, 2016, t. 2, en particular su comentario al art. 53.<\/p>\n\n\n\n<p><a href=\"#_ednref28\">[28]<\/a> C\u00e1m. Civ. Com. Lab. Min., Neuqu\u00e9n, sala I, 14\/05\/2019, \u201c<em>Sarmiento, Ram\u00f3n A. c\/ Lascialanda, Walter A. s\/ da\u00f1os y perjuicios<\/em>\u201d, La Ley Cita Online: AR\/JUR\/33059\/2019.<\/p>\n\n\n\n<p><a href=\"#_ednref29\">[29]<\/a> S.C.J.B.A., 01\/04\/2015, \u201c<em>G., A. C. c\/ Pasema S.A. y otros s\/da\u00f1os y perjuicios<\/em>\u201d, RCyS 2015-XII,&nbsp;47, Cita Online: AR\/JUR\/3008\/2015.<\/p>\n\n\n\n<p><a href=\"#_ednref30\">[30]<\/a> LORENZETTI, Ricardo L., <em>Consumidores<\/em>, Rubinzal-Culzoni editores, Santa Fe, 2009, p. 602.<\/p>\n\n\n\n<p><a href=\"#_ednref31\">[31]<\/a> Supuesto que tampoco ocurre en el \u00e1mbito de la teor\u00eda de las cargas probatorias din\u00e1micas, ver, PEYRANO, Jorge W., <em>Nuevos lineamientos de las cargas probatorias din\u00e1micas<\/em>, en PEYRANO, Jorge W. (director), <em>Cargas Probatorias Din\u00e1micas<\/em>, Rubinzal Culzoni editores, Santa Fe, 2008, pp. 25 y ss.<\/p>\n\n\n\n<p><a href=\"#_ednref32\">[32]<\/a> CNCom., sala F, 05\/10\/2010, \u201c<em>Playa Palace S.A. c\/ Pe\u00f1aloza, Leandro Hip\u00f3lito<\/em>\u201d, JA 2011-III, 397, Cita Online: AR\/JUR\/57936\/2010.<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-white-background-color has-text-color has-background\" style=\"color:#4a4a4b\"><tbody><tr><td><strong>C\u00f3mo citar este art\u00edculo:<\/strong><\/td><\/tr><tr><td>Raschetti, Franco (2021, septiembre). Prueba del da\u00f1o en acciones de consumo. <em>Ius in fieri DDA.<\/em> www.iusinfieri.com.ar<\/td><\/tr><\/tbody><\/table><\/figure>\n<div style=\"margin: 20px 0;\"><div class=\"qrcswholewtapper\" style=\"text-align:right;\"><div class=\"qrcprowrapper\"  id=\"qrcwraa2leds\"><div class=\"qrc_canvass\" id=\"qrc_cuttenpages_2\" style=\"display:inline-block\" data-text=\"https:\/\/iusinfieri.com.ar\/index.php\/2022\/02\/24\/prueba-del-dano-moral-en-acciones-de-consumo\/\"><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>SUMARIO: I. Proemio. Descripci\u00f3n metodol\u00f3gica. II. Generalidades del rubro indemnizatorio de marras. III. Prueba del da\u00f1o moral. IV. Los deberes del proveedor con relaci\u00f3n a la prueba. I. Proemio. Descripci\u00f3n metodol\u00f3gica En este op\u00fasculo procuraremos <a class=\"mh-excerpt-more\" href=\"https:\/\/iusinfieri.com.ar\/index.php\/2022\/02\/24\/prueba-del-dano-moral-en-acciones-de-consumo\/\" title=\"Prueba del da\u00f1o moral en acciones de consumo\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[23,12,4,13],"tags":[19,18],"class_list":{"0":"post-87","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-art","8":"category-consumidor","9":"category-dpr","10":"category-responsabilidad_civil","11":"tag-acciones-de-consumo","12":"tag-dano-moral"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":7,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"predecessor-version":[{"id":375,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/87\/revisions\/375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/media\/279"}],"wp:attachment":[{"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iusinfieri.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}